{"id":4759,"date":"2025-08-13T10:50:05","date_gmt":"2025-08-13T09:50:05","guid":{"rendered":"https:\/\/saint-christophers-hosting.com\/?p=4759"},"modified":"2025-08-14T09:15:06","modified_gmt":"2025-08-14T08:15:06","slug":"sculpteur-et-restaurateur","status":"publish","type":"post","link":"https:\/\/saint-christophers-hosting.com\/index.php\/2025\/08\/13\/sculpteur-et-restaurateur\/","title":{"rendered":"Sculpteur et Restaurateur"},"content":{"rendered":"<audio class=\"wp-audio-shortcode\" id=\"audio-4759-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"\/wp-content\/uploads\/2025\/08\/franceinfo-junior-du-samedi-09-aout.mp3?_=1\" \/><a href=\"\/wp-content\/uploads\/2025\/08\/franceinfo-junior-du-samedi-09-aout.mp3\">\/wp-content\/uploads\/2025\/08\/franceinfo-junior-du-samedi-09-aout.mp3<\/a><\/audio>\n[00:00] &#8211; Orateur<br \/>\n<strong>France Info.<\/strong><\/p>\n[00:03] &#8211; Les \u00e9l\u00e8ves<br \/>\n<strong>Bonjour. Nous sommes les \u00e9l\u00e8ves du coll\u00e8ge Anatole France \u00e0 Sarty dans la Manche. Et nous allons poser des questions \u00e0 un sculpteur.<\/strong><\/p>\n[00:10] &#8211; Orateur<br \/>\n<strong>Et oui, un sculpteur. \u00c0 vous Fran\u00e7ois Gilles, bonjour. Bonjour. Vous \u00eates sculpteur et restaurateur, aussi meilleur apprenti de France, agr\u00e9g\u00e9, normalien, vous r\u00e9novez, entre autres, des monuments class\u00e9s. Et les enfants ont plein de questions \u00e0 vous poser. Qui veut<br \/>\ncommencer ? \u00c0 toi, Donovan.<\/strong><\/p>\n[00:27] &#8211; Donovan<br \/>\n<strong>Pouvez-vous nous expliquer en quoi consiste votre m\u00e9tier ?<\/strong><\/p>\n[00:30] &#8211; Fran\u00e7ois Gilles<br \/>\n<strong>Le m\u00e9tier de sculpteur, en lui-m\u00eame, il consiste \u00e0 simplement cr\u00e9er des \u0153uvres en volume, normalement, par enl\u00e8vement de mati\u00e8re. On part d&#8217;un blog de quelque chose et on enl\u00e8ve de la mati\u00e8re dedans. Moi, je suis plus sp\u00e9cifiquement sculpteur sur bois, c&#8217;est-\u00e0 dire que je pars des arbres, je pars de planches de bois pour cr\u00e9er des \u0153uvres en volume et plus particuli\u00e8rement, effectivement, vous le disiez, pour des monuments historiques et beaucoup pour le d\u00e9cor int\u00e9rieur. Je fais beaucoup de restauration dans ce cadre-l\u00e0.<\/strong><\/p>\n[00:59] &#8211; Orateur<br \/>\n<strong>Et puis, dans l&#8217;actualit\u00e9 aussi, il y a, et \u00e7a, je sais que vous avez travaill\u00e9 en classe l\u00e0-dessus, les enfants, il y a la restitution de sculptures \u00e0 des pays colonis\u00e9s par la France, en fait, r\u00e9parer des erreurs du pass\u00e9, finalement. Restitution, par exemple, d&#8217;un tambour-parleur \u00e0 la C\u00f4te d&#8217;Ivoire. C&#8217;est une sculpture assez impressionnante de 430 kilos. Le S\u00e9nat a enclench\u00e9 tout un processus l\u00e0-dessus. \u00c7a, c&#8217;est important, Fran\u00e7ois Gilles, justement, quand une sculpture, \u00e7a fait partie de l&#8217;histoire d&#8217;un pays, qu&#8217;on revienne un peu l\u00e0-dessus sur ce pass\u00e9, m\u00eame si on est qu&#8217;au d\u00e9but du chemin.<\/strong><\/p>\n[01:29] &#8211; Fran\u00e7ois Gilles<br \/>\n<strong>C&#8217;est tout nouveau, effectivement, qu&#8217;on s&#8217;y int\u00e9resse du point de vue de la l\u00e9galit\u00e9. Th\u00e9oriquement, les collections nationales sont des collections qui sont inali\u00e9nables. C&#8217;est un gros mot pour dire que toute \u0153uvre qui rentre dans les collections nationales ne peut plus en sortir. Donc, \u00e0 partir du moment o\u00f9 on souhaite, pour une raison X ou Y, faire sortir une \u0153uvre des collections nationales, c&#8217;est qu&#8217;effectivement, il faut passer devant le Parlement, il faut passer par la loi et c&#8217;est l\u00e0 encore un geste politique. Donc, \u00e7a veut dire qu&#8217;effectivement, au cas par cas, dans le cas de ces pays il faut pouvoir \u00e9tudier si les \u0153uvres ont \u00e9t\u00e9 acquises de mani\u00e8re frauduleuse ou non. Et si on a la preuve, effectivement, que les \u0153uvres sont acquises de mani\u00e8re frauduleuse, dans l&#8217;absolu, il n&#8217;y a pas de raison de ne pas les rendre.<\/strong><\/p>\n[02:10] &#8211; Donovan<br \/>\n<strong>Pourquoi rendre le mal\u00e9fait ?<\/strong><\/p>\n[02:11] &#8211; Fran\u00e7ois Gilles<br \/>\n<strong>On peut consid\u00e9rer que les mus\u00e9es sont universels et que donc, ils sont au-dessus de l&#8217;histoire, ils sont au-dessus des consid\u00e9rations politiques et que donc, ils prot\u00e8gent la m\u00e9moire du monde, y compris la mauvaise m\u00e9moire du monde, j&#8217;allais dire presque m\u00eame la mauvaise conscience du monde. Le probl\u00e8me est que dans le cas de certains pays, quasiment tout leur patrimoine, pour le coup, leur a \u00e9t\u00e9 spoli\u00e9. Et donc, m\u00eame si on ne sort pas certaines collections ou certaines \u0153uvres des collections publiques, il faut poser la question de les red\u00e9poser et de les re-rendre visibles de nouveau dans ces pays-l\u00e0.<\/strong><\/p>\n[02:46] &#8211; Donovan<br \/>\n<strong>Pouvez-vous nous citer quelques \u0153uvres connues qui ont \u00e9t\u00e9 restitu\u00e9es \u00e0 l&#8217;heure actuelle ?<\/strong><\/p>\n[02:52] &#8211; Fran\u00e7ois Gilles<br \/>\n<strong>Dans les \u0153uvres qui ont fait l&#8217;actualit\u00e9, il y a par exemple l&#8217;affaire, \u00c7a a \u00e9t\u00e9 une affaire, maintenant, \u00e7a n&#8217;en est plus vraiment une, mais des manuscrits cor\u00e9ens dans le cadre de repr\u00e9sailles qui ont \u00e9t\u00e9 men\u00e9es par l&#8217;Arm\u00e9e Fran\u00e7aise contre la Cor\u00e9e, qui avaient massacr\u00e9 des missionnaires j\u00e9suites sous Napol\u00e9on III, sous le Second Empire, des manuscrits ont \u00e9t\u00e9 pris en Cor\u00e9e et mis dans les collections de la Biblioth\u00e8que nationale de France. Ces manuscrits, dans le cadre de bonnes relations diplomatiques, ont \u00e9t\u00e9 rendus \u00e0 la Cor\u00e9e. Toujours sur ce cas des manuscrits cor\u00e9ens, les conservateurs de la Biblioth\u00e8que Nationale de France ont refus\u00e9 de rendre ces manuscrits, donc il a fallu quasiment leur prendre de force. Les politiques, lors de ce voyage diplomatique, ont d\u00fb r\u00e9cup\u00e9rer la mallette dans lesquelles il y avait les manuscrits. Les conservateurs n&#8217;ont pas voulu donner la cl\u00e9, donc il a fallu forcer la serrure. Il y a eu toute une affaire comme \u00e7a qui a un petit peu d&#8217;ailleurs aussi traumatis\u00e9 le monde des mus\u00e9es, parce qu&#8217;il faut bien s&#8217;imaginer que les conservateurs du patrimoine qui s&#8217;occupent des collections des mus\u00e9es, eux, ce qu&#8217;on leur apprend, c&#8217;est \u00e0 prot\u00e9ger les collections qu&#8217;on leur confie, quelle que soit leur histoire, d&#8217;une certaine mani\u00e8re.<\/strong><\/p>\n[04:06] &#8211; Orateur<br \/>\n<strong>Merci beaucoup, Fran\u00e7ois Gilles, d&#8217;\u00eatre venu dans le studio de France Info Junior pour r\u00e9pondre aux questions des enfants sur votre m\u00e9tier de sculpteur, sur la restitution des biens culturels. \u00c9galement, France Info Junior. Une \u00e9mission \u00e0 retrouver sur https:\/\/franceinfo.fr et l&#8217;appli&#8217; Radio France, pr\u00e9par\u00e9e par Estelle Faure et Jeanne Sarfati-Camarek.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[00:00] &#8211; Orateur France Info. [00:03] &#8211; Les \u00e9l\u00e8ves Bonjour. Nous sommes les \u00e9l\u00e8ves du coll\u00e8ge Anatole France \u00e0 Sarty dans la Manche. Et nous allons poser des questions \u00e0 un sculpteur. [00:10] &#8211; Orateur Et oui, un sculpteur. \u00c0&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"https:\/\/saint-christophers-hosting.com\/index.php\/2025\/08\/13\/sculpteur-et-restaurateur\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":4718,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-4759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-french"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2025\/05\/franceinfo-junior-Pourquoi-une-taxe-mp3-image.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8rlea-1eL","_links":{"self":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/4759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/comments?post=4759"}],"version-history":[{"count":6,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/4759\/revisions"}],"predecessor-version":[{"id":4766,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/4759\/revisions\/4766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/media\/4718"}],"wp:attachment":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/media?parent=4759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/categories?post=4759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/tags?post=4759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}