{"id":4578,"date":"2025-02-12T21:56:09","date_gmt":"2025-02-12T21:56:09","guid":{"rendered":"https:\/\/saint-christophers-hosting.com\/?p=4578"},"modified":"2025-02-12T22:20:50","modified_gmt":"2025-02-12T22:20:50","slug":"le-bonheur","status":"publish","type":"post","link":"https:\/\/saint-christophers-hosting.com\/index.php\/2025\/02\/12\/le-bonheur\/","title":{"rendered":"Le bonheur"},"content":{"rendered":"<p><a href=\"https:\/\/enseigner.tv5monde.com\/fiches-pedagogiques-fle\/le-bonheur\" target=\"_blank\" rel=\"noopener\">https:\/\/enseigner.tv5monde.com\/fiches-pedagogiques-fle\/le-bonheur<\/a><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-4578-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"\/wp-content\/uploads\/2025\/02\/Archimede-Le-bonheur-Clip-officiel.mp3?_=1\" \/><a href=\"\/wp-content\/uploads\/2025\/02\/Archimede-Le-bonheur-Clip-officiel.mp3\">\/wp-content\/uploads\/2025\/02\/Archimede-Le-bonheur-Clip-officiel.mp3<\/a><\/audio>\n<p>Qu\u2019importe que tu ne sois qu\u2019un looser<br \/>\nSans Rolex \u00e0 ton bras<br \/>\nL\u2019important c\u2019est ton bras<\/p>\n<p>Qu\u2019importe si dipl\u00f4m\u00e9 d\u2019un Master<br \/>\nTu livres encore des pizzas<br \/>\nLe bonheur n\u2019est-il pas ailleurs ?<\/p>\n<p>Dans les seins qu\u2019on p\u00e9trit<br \/>\nDans les contrep\u00e8teries<br \/>\nDans l\u2019art d\u2019\u00eatre incompris<\/p>\n[Refrain]\n<p>Le bonheur est \u00e0 la port\u00e9e de tous<br \/>\nMais rien ne dit dans le Larousse<br \/>\nComment s\u2019y prendre<\/p>\n<p>Le bonheur est \u00e0 la port\u00e9e de tous<br \/>\nM\u00eame les moches, m\u00eame les rousses<br \/>\nPeuvent y pr\u00e9tendre<\/p>\n<p>Qu\u2019importe que tu ne sois pas ce footballeur<br \/>\nQui palpe un million par mois<br \/>\nTu roules en Porsche sur PS3<\/p>\n<p>Qu\u2019importe si tu n\u2019aimes pas tes rondeurs<br \/>\nNous autres on les aime pour toi<br \/>\nLe bonheur n\u2019est-il pas d\u2019ailleurs ?<\/p>\n<p>Dans les seins qu\u2019on p\u00e9trit<br \/>\nDans les cartons qu\u2019on plie<br \/>\nDans les cartes que l\u2019on d\u00e9plie<\/p>\n[Refrain]\n<p>Tant qu\u2019il est vrai que le bonheur est tol\u00e9rant<br \/>\nQu\u2019il fond de surcroit au hasard sur la plupart des gens<\/p>\n[Refrain]\n<p>Qu\u2019importe que tu ne sois qu\u2019un looser<br \/>\nSans Rolex \u00e0 ton bras<br \/>\nL\u2019important c\u2019est ton bras<\/p>\n<p>Qu\u2019importe que tu ne sois pas cet acteur bankable de cin\u00e9ma<br \/>\nLe bonheur c\u2019est pas \u00e7a<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/enseigner.tv5monde.com\/fiches-pedagogiques-fle\/le-bonheur Qu\u2019importe que tu ne sois qu\u2019un looser Sans Rolex \u00e0 ton bras L\u2019important c\u2019est ton bras Qu\u2019importe si dipl\u00f4m\u00e9 d\u2019un Master Tu livres encore des pizzas Le bonheur n\u2019est-il pas ailleurs ? Dans les seins qu\u2019on p\u00e9trit Dans les&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"https:\/\/saint-christophers-hosting.com\/index.php\/2025\/02\/12\/le-bonheur\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":4422,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-4578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-french"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2024\/10\/tv5MondePlus.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8rlea-1bQ","_links":{"self":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/4578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/comments?post=4578"}],"version-history":[{"count":3,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/4578\/revisions"}],"predecessor-version":[{"id":4584,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/4578\/revisions\/4584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/media\/4422"}],"wp:attachment":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/media?parent=4578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/categories?post=4578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/tags?post=4578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}