{"id":3302,"date":"2023-05-04T15:02:43","date_gmt":"2023-05-04T14:02:43","guid":{"rendered":"https:\/\/saint-christophers-hosting.com\/?p=3302"},"modified":"2023-05-04T15:02:43","modified_gmt":"2023-05-04T14:02:43","slug":"etats-unis-fractures-dhier-et-daujourdhui","status":"publish","type":"post","link":"https:\/\/saint-christophers-hosting.com\/index.php\/2023\/05\/04\/etats-unis-fractures-dhier-et-daujourdhui\/","title":{"rendered":"\u00c9tats-Unis : fractures d&#8217;hier et d&#8217;aujourd&#8217;hui"},"content":{"rendered":"<p><a title=\"le dessous des cartes\" href=\"https:\/\/www.arte.tv\/fr\/videos\/108458-021-A\/le-dessous-des-cartes\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.arte.tv\/fr\/videos\/108458-021-A\/le-dessous-des-cartes\/<\/a><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-3302-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2023\/05\/Etats-Unis-Fracture-01.mp3?_=1\" \/><a href=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2023\/05\/Etats-Unis-Fracture-01.mp3\">https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2023\/05\/Etats-Unis-Fracture-01.mp3<\/a><\/audio>\n[0:16] &#8211; Emilie<br \/>\nRavie d&#8217;en trouver pour ce nouveau num\u00e9ro du Dessous des cartes. Aujourd&#8217;hui, on prend la direction des \u00c9tats-Unis en commen\u00e7ant par cette image.<br \/>\nNovembre 2016, la Maison Blanche et la passation de pouvoir que peu d&#8217;observateurs avaient vu venir. Le premier pr\u00e9sident noir de l&#8217;histoire am\u00e9ricaine, le d\u00e9mocrate Barack Obama, actant la d\u00e9faite d&#8217;Hillary Clinton et remettant les cl\u00e9s de la premi\u00e8re puissance du monde au milliardaire r\u00e9publicain Donald Trump apr\u00e8s une campagne folle marqu\u00e9e par de nombreux d\u00e9rapages. Une \u00e9lection soulignant comme jamais des \u00c9tats D\u00e9sunis. Une Am\u00e9rique coup\u00e9e en deux qu&#8217;on retrouve \u00e9galement dans les derniers scrutins. Novembre 2020, Joe Biden \u00e9lu de peu. Lors des mid-terms de novembre 2022, le S\u00e9nat sauv\u00e9 in extremis par les d\u00e9mocrates. Bref, une \u00e9galit\u00e9 quasi statistique d\u00e9sormais entre les deux Am\u00e9riques o\u00f9 tout se joue donc sur le fil et dans un climat de grandes tensions. L&#8217;occasion pour nous d&#8217;essayer de comprendre d&#8217;o\u00f9 viennent ces fractures. De l&#8217;installation des premiers colons, \u00e0 la guerre de S\u00e9cession jusqu&#8217;au d\u00e9bat actuel sur l&#8217;avortement, on va se demander si les Am\u00e9ricains ne rejouent pas au fond, r\u00e9guli\u00e8rement, des divisions qui, on va le voir, viennent de loin, sortons nos cartes.<\/p>\n[1:27] &#8211; Emilie<br \/>\nCommen\u00e7ons en 1607, lorsque 104 hommes d\u00e9barquent en Virginie \u00e0 un lieu qu&#8217;ils nomment Jamestown. En 1620, plus au nord, Plymouth est fond\u00e9e par les colons d\u00e9barqu\u00e9s du c\u00e9l\u00e8bre Mayflower. Tr\u00e8s vite, ces deux colonies vont \u00e9voluer de fa\u00e7on diff\u00e9rente. Au Sud, la Virginie est caract\u00e9ris\u00e9e par une \u00e9conomie de plantations et une population majoritairement masculine. Le climat est chaud et les sols fertiles. La religion officielle est la religion anglicane. Au Nord, la Nouvelle Angleterre est fond\u00e9e par des colons en rupture avec l&#8217;\u00e9glise d&#8217;Angleterre. On y recense une immigration familiale et l&#8217;\u00e9conomie tourn\u00e9e vers la p\u00eache, l&#8217;exploitation foresti\u00e8re et le commerce. D&#8217;environ 250.000 habitants en 1700, la population va atteindre les 2,5 millions en 1776. Cette pression d\u00e9mographique s&#8217;accompagne d&#8217;une pouss\u00e9e vers l&#8217;int\u00e9rieur des terres, mais en 1763, la Couronne \u00e9dicte une ligne au-del\u00e0 de laquelle les colons ne peuvent pas s&#8217;installer. \u00c0 cela s&#8217;ajoute une pression fiscale impos\u00e9e par l&#8217;Angleterre. La soci\u00e9t\u00e9 coloniale se divise alors entre les partisans de la R\u00e9sistance \u00e0 Londres, les loyalistes, et une majorit\u00e9 des ind\u00e9cis. La guerre contre l&#8217;Angleterre va durer de 1775 \u00e0 1783, mais l&#8217;ind\u00e9pendance est proclam\u00e9e d\u00e8s le 4 juillet 1776. Une Ind\u00e9pendance qui aurait d\u00fb cimenter cette jeune nation, mais \u00e0 l&#8217;inverse, deux tendances se dessinent.<\/p>\n[2:56] &#8211; Emilie<br \/>\nLes partisans d&#8217;un \u00c9tat f\u00e9d\u00e9ral fort et ceux qui d\u00e9fendent au contraire le droit des \u00c9tats. En 1787, une nouvelle constitution \u00e9tablit une f\u00e9d\u00e9ration qui tente d&#8217;\u00e9quilibrer les pouvoirs entre les \u00c9tats f\u00e9d\u00e9r\u00e9s et l&#8217;\u00c9tat f\u00e9d\u00e9ral. D\u00e8s lors, la conqu\u00eate de l&#8217;ensemble du continent d\u00e9marre, une expansion qui, bien que glorifi\u00e9e, porte d\u00e9j\u00e0 en elle les maux du futur. Une opposition Nord-Sud se creuse du fait de leur d\u00e9veloppement \u00e0 des rythmes diff\u00e9rents. Au Nord, en effet, l&#8217;industrialisation est rapide et concentr\u00e9e. Le Sud, lui, s&#8217;\u00e9tend et devient producteur, notamment, de coton. La population se divise. Il y a d&#8217;une part les esclaves 700.000 en 1790, 4 millions en 1860, et d&#8217;autre part les esclavagistes et les anti esclavagistes ou abolitionnistes. Des abolitionnistes qui s&#8217;emploient, entre autres, \u00e0 exfiltrer des \u00e9tats esclavagistes, les esclaves fugitifs. Cette opposition aboutit \u00e0 la guerre de S\u00e9cession, une guerre civile qui durera de 1861 \u00e0 1865, avec plus de 750.000 morts, soit 2% de la population. Le Nord va gagner la guerre, mais pas la paix. Le Sud, ravag\u00e9, reste occup\u00e9 militairement pendant 12 ann\u00e9es et les progr\u00e8s sont minces. \u00c0 l&#8217;esclavage, succ\u00e8de la s\u00e9gr\u00e9gation. La fin de la conqu\u00eate du continent se fait par l&#8217;exploitation de l&#8217;Ouest.<\/p>\n[4:20] &#8211; Emilie<br \/>\nMise en place de voies de communication et exploitation des ressources, cette conqu\u00eate se fait aussi sur le d\u00e9racinement et l&#8217;enfermement dans des r\u00e9serves du peuple am\u00e9rindien. Par ailleurs, le pays fait face \u00e0 une immigration consid\u00e9rable. La population, qui avait d\u00e9j\u00e0 tripl\u00e9 entre 1820 et 1860, triple \u00e0 nouveau entre 1860 et 1910. Cette immigration suscite des r\u00e9actions hostiles des Am\u00e9ricains qui se consid\u00e8rent d&#8217;origine les WASP, White Anglo Saxon Protestants, et qui rejettent en masse ces nouveaux arrivants. \u00c0 l&#8217;ouest, l&#8217;immigration chinoise, bien que minoritaire, est \u00e0 l&#8217;origine de la premi\u00e8re loi migratoire, le Chinese Exclusion Act de 1882. \u00c0 l&#8217;est, le centre d&#8217;Ellis Island est cr\u00e9\u00e9 en 1892 et l&#8217;entr\u00e9e dans le pays est conditionn\u00e9e au passage d&#8217;un test de lecture. On l&#8217;aura compris, les \u00c9tats-Unis se sont construits sur de fortes divisions. C&#8217;est aussi cette capacit\u00e9 \u00e0 les surmonter qui a ciment\u00e9 l&#8217;esprit et la fiert\u00e9 des Am\u00e9ricains. Pourtant, ces divisions historiques se retrouvent encore aujourd&#8217;hui et c&#8217;est ce qu&#8217;on va voir maintenant en nous projetant directement en 2016 dans l&#8217;Am\u00e9rique de Donald Trump. C&#8217;est \u00e0 la surprise g\u00e9n\u00e9rale que le milliardaire de Floride est \u00e9lu. Constat imm\u00e9diat, Trump b\u00e9n\u00e9ficie du clivage origine entre le Nord et le Sud.<\/p>\n[5:41] &#8211; Emilie<br \/>\nAinsi, les \u00c9tats du Sud, qui ont vot\u00e9 pour lui, sont ceux qui pratiquaient autrefois la s\u00e9gr\u00e9gation raciale. Mais fait nouveau, la victoire de Trump s&#8217;est aussi jou\u00e9e \u00e0 quelques milliers de voix dans les bastions historiquement d\u00e9mocrates de ce que l&#8217;on appelle la Rust Belt, c&#8217;est \u00e0 dire la ceinture de rouille, r\u00e9gion industrielle en fort d\u00e9clin. L&#8217;\u00e9lection de Trump donne aussi \u00e0 voir un pays scind\u00e9 entre une Am\u00e9rique plus rurale, plus conservatrice et un pays plus urbain tourn\u00e9 vers le progr\u00e8s. Une division entre le centre et les c\u00f4tes. En effet, sur les 333 millions d&#8217;habitants que compte le pays, pr\u00e8s de 250 millions vivent dans des zones urbaines ou \u00e0 proximit\u00e9. Et c&#8217;est dans la plupart de ces grandes villes que se trouve le vote d\u00e9mocrate. Une division du pays que l&#8217;on retrouve aussi avec un autre marqueur fort de la soci\u00e9t\u00e9 am\u00e9ricaine, la r\u00e9glementation de l&#8217;avortement. Mais avant d&#8217;aller plus loin dans l&#8217;\u00e9tude de cette carte, arr\u00eatons-nous un instant sur la Cour Supr\u00eame, h\u00e9ritage de la Constitution de 1787. Il s&#8217;agit de la plus haute juridiction du pays et depuis 1869, elle compte neuf membres d\u00e9sign\u00e9s \u00e0 vie par le pr\u00e9sident. Ce dernier est cens\u00e9 choisir une personnalit\u00e9 avec qui il partage des affinit\u00e9s politiques et id\u00e9ologiques, mais aussi suffisamment mod\u00e9r\u00e9es pour que soit garantie l&#8217;\u00e9quilibre des pouvoirs.<\/p>\n[7:02] &#8211; Emilie<br \/>\nSauf que durant son mandat, Trump a d\u00e9sign\u00e9 trois des neuf juges qui si\u00e8gent actuellement \u00e0 la Cour supr\u00eame, trois juges ultra conservateurs qui font durablement basculer la Cour. Ainsi, le 24 juin 2022, l&#8217;une des premi\u00e8res d\u00e9cisions de cette Cour a \u00e9t\u00e9 le renversement de la jurisprudence Roe versus Wade de 1973. Cons\u00e9quence, ce sont d\u00e9sormais les \u00c9tats qui l\u00e9gif\u00e8rent sur le droit \u00e0 l&#8217;avortement, lequel n&#8217;est plus prot\u00e9g\u00e9 au niveau f\u00e9d\u00e9ral. Regardez cette carte. On peut y voir les \u00c9tats qui ont interdit ou tr\u00e8s fortement restreint depuis l&#8217;avortement, voire qui l&#8217;ont criminalis\u00e9. Ainsi, en Oklahoma, en plus de son interdiction, toute personne ayant pratiqu\u00e9 l&#8217;IVG ou tent\u00e9 de le faire s&#8217;expose \u00e0 une peine pouvant s&#8217;\u00e9lever \u00e0 10 ans d&#8217;emprisonnement et 100.000 dollars d&#8217;amende. Inversement, la Californie et l&#8217;Oregon sur la C\u00f4te West et les \u00c9tats de la c\u00f4te nord est ont d\u00e9cid\u00e9 de prot\u00e9ger l&#8217;acc\u00e8s \u00e0 l&#8217;avortement. Ce clivage, socio g\u00e9ographique traditionnel est malgr\u00e9 tout en train d&#8217;\u00e9voluer, notamment dans des \u00c9tats traditionnellement r\u00e9publicains, mais \u00e0 fortes populations \u00e9trang\u00e8res. C&#8217;est ce qu&#8217;on a pu observer \u00e0 l&#8217;occasion de la lutte contre la politique anti-immigration clandestine de Trump. Entre 2017 et 2020, des comt\u00e9s, des villes et des \u00c9tats se sont d\u00e9clar\u00e9s sanctuaires, c&#8217;est \u00e0 dire refusant de collaborer avec l&#8217;Agence d&#8217;\u00c9tat charg\u00e9e d&#8217;appr\u00e9hender les sans-papiers.<\/p>\n[8:27] &#8211; Emilie<br \/>\nDans cette lutte, on retrouve bien s\u00fbr les \u00c9tats d\u00e9mocrates c\u00f4tiers ainsi que le Nouveau Mexique et le Colorado, traditionnellement d\u00e9mocrates. Mais on trouve \u00e9galement la Floride et c&#8217;est un fait nouveau. Bien que traditionnellement r\u00e9publicaine, la Floride est aussi un \u00c9tat \u00e0 forte population \u00e9trang\u00e8re. Et ce m\u00e9tissage entra\u00eene des comportements sociaux, \u00e9lectoraux et politiques nouveaux. D&#8217;ailleurs, dans sa globalit\u00e9, cette carte des sanctuaires, regardez, recoupe celle de 2019 sur la part de populations n\u00e9es \u00e0 l&#8217;\u00e9tranger. Arr\u00eatons-nous sur ce m\u00e9tissage de la soci\u00e9t\u00e9 am\u00e9ricaine. Les \u00c9tats-Unis, on l&#8217;a vu, sont une nation d&#8217;immigrants. Entre 1960 et 2022, on compte plus de 65 millions d&#8217;immigrants, principalement d&#8217;Am\u00e9rique latine et d&#8217;Asie. En r\u00e9sulte, une profonde transformation du pays, qui passe d&#8217;une population majoritairement blanche, enracin\u00e9e, \u00e0 une soci\u00e9t\u00e9 diversifi\u00e9e, faite de plusieurs minorit\u00e9s et qui font bouger les divisions traditionnelles. Ce terme de minorit\u00e9, il fait r\u00e9f\u00e9rence \u00e0 quatre grands groupes. Les Hispaniques, presque 19% de la population, les Afro am\u00e9ricains, 12%, les Asiatiques et insulaires du Pacifique, 8%et les Am\u00e9rindiens et autochtones d&#8217;Alaska, 1%. Dans certaines zones, l&#8217;une ou l&#8217;autre minorit\u00e9 est dominante, de m\u00eame que dans certaines villes, ainsi la minorit\u00e9 asiatique \u00e0 Seattle ou \u00e0 Portland ou hispanique \u00e0 Austin, San Antonio et Houston.<\/p>\n[10:01] &#8211; Emilie<br \/>\nD&#8217;ailleurs, entre 1990 et 2020, la croissance la plus rapide est celle des Hispaniques, avec +23%. Enfin, il y a des d\u00e9bats qui font exploser tous ces clivages de la soci\u00e9t\u00e9 am\u00e9ricaine. Celle des mobilisations massives du mouvement Black Lives Matter, n\u00e9e en 2013 pour d\u00e9noncer le racisme envers les Noirs et qui faisait suite \u00e0 l&#8217;acquittement de l&#8217;assassin d&#8217;un adolescent noir, Trayvon Martin. Entre mai et octobre 2020, environ 15 \u00e0 26 millions de personnes participent sur l&#8217;ensemble du territoire aux manifestations li\u00e9es \u00e0 la mort de George Floyd. Cela fait de ces protestations le plus grand mouvement de l&#8217;histoire du pays. Le mouvement des droits civiques des ann\u00e9es 1960 \u00e9tait rest\u00e9 beaucoup plus modeste en nombre de manifestants. Clivage ancestral entre le Nord et le Sud, division entre l&#8217;Am\u00e9rique du Centre et l&#8217;Am\u00e9rique des c\u00f4tes. On voit bien \u00e0 travers le temps comment se sont structur\u00e9s ces clivages sociog\u00e9ographiques des \u00c9tats-Unis. M\u00eame si, on l&#8217;a dit, ces clivages \u00e9voluent aussi au gr\u00e9 du m\u00e9tissage de la soci\u00e9t\u00e9 am\u00e9ricaine. Il est enfin aujourd&#8217;hui une ultime fracture, sans doute la plus inqui\u00e9tante, celle qui place d\u00e9sormais, en dehors du jeu d\u00e9mocratique, une certaine frange de l&#8217;Am\u00e9rique, tr\u00e8s active sur les r\u00e9seaux sociaux, notamment.<\/p>\n[11:17] &#8211; Emilie<br \/>\nDes Am\u00e9ricains qui ne respectent plus le verdict des urnes, ne croient plus les m\u00e9dias traditionnels, adh\u00e8rent \u00e0 des th\u00e9ories du complot. Ceux qui, le 6 janvier 2021, ont pris d&#8217;assaut le Capitole, faisant vaciller comme jamais la d\u00e9mocratie am\u00e9ricaine.<\/p>\n[11:32] &#8211; Emilie<br \/>\nNous avons pr\u00e9par\u00e9 avec lui cette \u00e9mission le sp\u00e9cialiste de la Soci\u00e9t\u00e9 de la politique am\u00e9ricaine. Jean \u00c9ric Brana publie cette g\u00e9opolitique des \u00c9tats-Unis chez PUF.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/www.arte.tv\/fr\/videos\/108458-021-A\/le-dessous-des-cartes\/ [0:16] &#8211; Emilie Ravie d&#8217;en trouver pour ce nouveau num\u00e9ro du Dessous des cartes. Aujourd&#8217;hui, on prend la direction des \u00c9tats-Unis en commen\u00e7ant par cette image. Novembre 2016, la Maison Blanche et la passation de pouvoir que peu d&#8217;observateurs&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"https:\/\/saint-christophers-hosting.com\/index.php\/2023\/05\/04\/etats-unis-fractures-dhier-et-daujourdhui\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":1395,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-3302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-french"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2020\/11\/arte-tv.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8rlea-Rg","_links":{"self":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/3302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/comments?post=3302"}],"version-history":[{"count":1,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/3302\/revisions"}],"predecessor-version":[{"id":3303,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/3302\/revisions\/3303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/media\/1395"}],"wp:attachment":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/media?parent=3302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/categories?post=3302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/tags?post=3302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}