{"id":3147,"date":"2023-02-07T11:02:37","date_gmt":"2023-02-07T11:02:37","guid":{"rendered":"https:\/\/saint-christophers-hosting.com\/?p=3147"},"modified":"2023-03-13T18:10:47","modified_gmt":"2023-03-13T18:10:47","slug":"la-chandeleur","status":"publish","type":"post","link":"https:\/\/saint-christophers-hosting.com\/index.php\/2023\/02\/07\/la-chandeleur\/","title":{"rendered":"La Chandeleur"},"content":{"rendered":"<div style=\"width: 752px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-3147-1\" width=\"752\" height=\"423\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"\/wp-content\/uploads\/2023\/02\/LaChandeleur.mp4?_=1\" \/><a href=\"\/wp-content\/uploads\/2023\/02\/LaChandeleur.mp4\">\/wp-content\/uploads\/2023\/02\/LaChandeleur.mp4<\/a><\/video><\/div>\n[0:04] &#8211; Animatrice<br \/>\n<strong>Qui de mieux que les Bretons pour nous raconter l&#8217;incroyable histoire de la Chandeleur ?<\/strong><\/p>\n[0:09] &#8211; Fran\u00e7oise<br \/>\n<strong>Moi, je viens du Morbihan, moi je suis originaire de la presqu&#8217;\u00eele de Rhuys.<\/strong><\/p>\n[0:15] &#8211; Rolande<br \/>\n<strong>Moi je suis du Centre Bretagne, pr\u00e8s de la for\u00eat de Broc\u00e9liande. La for\u00eat du roi Arthur et de l&#8217;enchanteur merlin.<\/strong><\/p>\n[0:24] &#8211; Olivier<br \/>\n<strong>Moi, je viens de la c\u00f4te de granit rose de Perros-Guirec.<\/strong><\/p>\n[0:30] &#8211; Animatrice<br \/>\n<strong>Ces quatre Bretons ont un point commun, ils f\u00eatent tous la Chandeleur \u00e0 Paris car ils y vivent. Apr\u00e8s la Bretagne, l&#8217;Ile de France compte la plus importante communaut\u00e9 bretonne du pays.<\/strong><\/p>\n[0:41] &#8211; Fran\u00e7oise<br \/>\n<strong>A Paris, quand il fait gris, il fait gris point, et le gris est gris. Alors qu&#8217;en fait, en Bretagne, vous aviez une esp\u00e8ce de cama\u00efeu de gris parce que c&#8217;est du gris &#8230;<\/strong><\/p>\n[0:51] &#8211; Animatrice<br \/>\n<strong>Les Bretons sont intarissables quand il s&#8217;agit de la r\u00e9gion. Peuple de marins et de voyageurs. Ils ont diffus\u00e9 partout en France leur meilleure recette de cr\u00eapes.<\/strong><\/p>\n[1:02] &#8211; Olivier<br \/>\n<strong>Bonjour Pascal, Bonjour, \u00e7a va bien tu vois ? En tout cas, mets-toi bien le voyage. Oui, super super !<\/strong><\/p>\n[1:10] &#8211; Animatrice<br \/>\n<strong>Hier, Pascal, fabricant de cr\u00eapes en Bretagne, a parcouru pr\u00e8s de 400 kilom\u00e8tres pour pouvoir livrer \u00e0 temps Olivier dans son \u00e9picerie parisienne o\u00f9 on ne trouve que des produits bretons.<\/strong><\/p>\n[1:21] &#8211; Pascale<br \/>\n<strong>J&#8217;ai pris la route, fin de matin\u00e9e, pour arriver &#8230; les livrer toute fra\u00eeche.<\/strong><\/p>\n[1:26] &#8211; Olivier<br \/>\n<strong>Comme beaucoup de Bretons exil\u00e9s, loin des produits qu&#8217;on aime consommer. J&#8217;avais un peu de mal \u00e0 les trouver qu&#8217;ici, c&#8217;est un peu comme si vous \u00e9tiez en Bretagne. Il y a plus de 10 % des gens d&#8217;\u00cele de France qui ont une origine bretonne 10 % sur 12 millions d&#8217;habitants en \u00cele de France, \u00e7a fait pas mal de monde et ils ne sont pas tous venus encore \u00e0 la boutique.<\/strong><\/p>\n[1:46] &#8211; Animatrice<br \/>\n<strong>La Chandeleur a lieu 40 jours apr\u00e8s No\u00ebl. Elle c\u00e9l\u00e8bre la pr\u00e9sentation de l&#8217;enfant J\u00e9sus au Temple. Mais avant d&#8217;\u00eatre chr\u00e9tienne, c&#8217;\u00e9tait une f\u00eate pa\u00efenne.<\/strong><\/p>\n[1:56] &#8211; Rolande<br \/>\n<strong>A la Chandeleur, le printemps commence \u00e0 rena\u00eetre. \u00c7a repr\u00e9sente la naissance de la vie. C&#8217;est le soleil. C&#8217;\u00e9tait la f\u00eate des chandelles.<\/strong><\/p>\n[2:05] &#8211; Animatrice<br \/>\n<strong>On mange des cr\u00eapes \u00e0 la Chandeleur depuis le VII\u1d49 si\u00e8cle, gr\u00e2ce au pape G\u00e9lase I\u1d49\u02b3 qui r\u00e9confortait les p\u00e8lerins de Rome avec des galettes, symbole de soleil et de moisson abondante. En Bretagne cette tradition n&#8217;est pas la seule qui subsiste.<\/strong><\/p>\n[2:20] &#8211; Rolande<br \/>\n<strong>Pour devenir riche, on prend une pi\u00e8ce dans la main gauche, on fait sauter les cr\u00eapes. Si on r\u00e9ussit, c&#8217;est qu&#8217;on aura du bonheur toute l&#8217;ann\u00e9e. Et en Bretagne, souvent, on laissait une cr\u00eape sur le haut de l&#8217;armoire.<\/strong><\/p>\n[2:32] &#8211; Animatrice<br \/>\n<strong>Le fief des Bretons \u00e0 Paris, c&#8217;est le quartier autour de la gare Montparnasse. Au XIX\u1d49 si\u00e8cle avec l&#8217;av\u00e8nement du chemin de fer, ils y arrivent par milliers pour chercher du travail.<\/strong><\/p>\n[2:44] &#8211; Fran\u00e7oise<br \/>\n<strong>Ils arrivaient, ils \u00e9taient pauvres, ils n&#8217;avaient pas de formation, ils parlaient mal le fran\u00e7ais. Une de mes tantes s&#8217;appelait Yvonne et quand elle est arriv\u00e9e, on l&#8217;a d\u00e9baptis\u00e9. On l&#8217;appelait Catherine parce qu&#8217;Yvonne, \u00e7a faisait trop breton. C&#8217;\u00e9tait l&#8217;\u00e9poque, on n&#8217;aimait pas e^tre breton, c&#8217;\u00e9tait le syndrome du plouc.<\/strong><\/p>\n[3:04] &#8211; Animatrice<br \/>\n<strong>Plouc. Voil\u00e0 un terme int\u00e9ressant. C&#8217;est comme \u00e7a que les Parisiens moqueurs, nommaient les Bretons en exil. \u00c7a vient du mot plou qui signifie paroisse en breton, que l&#8217;on retrouve en pr\u00e9fixe de nombreux villages Plougastel, Plouharnel, Ploumanac&#8217;h ou encore Plouhinec.<\/strong><\/p>\n[3:21] &#8211; Fran\u00e7oise<br \/>\n<strong>Le Plouc. Si, par assimilation, oui, l&#8217;habitant de la paroisse bretonne \u00e9videmment, avec une connotation extr\u00eamement n\u00e9gative, parce que le plouc, c&#8217;est celui qui est un peu crott\u00e9, qui n&#8217;est pas sorti du fin fond de son bocage.<\/strong><\/p>\n[3:35] &#8211; Animatrice<br \/>\n<strong>Et pourtant, ce sont ces m\u00eames Bretons de Paris qui ont d\u00e9mocratis\u00e9 les cr\u00eapes en ouvrant des cr\u00eaperies partout en France, et notamment dans le 14\u1d49 arrondissement. Celle de Rolande et sa fille Sol\u00e8ne existe depuis 1937.<\/strong><\/p>\n[3:49] &#8211; Sol\u00e8ne<br \/>\n<strong>Moi, mes enfants, c&#8217;est la cr\u00eape au sucre. La cr\u00eape au sucre comme une cr\u00eape bien faite. Moi je dis pour le plus simple appareil. Alors un petit peu de sucre pour 250 grammes de farine. Moi je mets six ou sept pour que la p\u00e2te \u00e0 cr\u00eapes soit soupe, quand vous faites vos craintes que \u00e7a ne vienne pas du carton.<\/strong><\/p>\n[4:07] &#8211; Animatrice<br \/>\n<strong>Mettre beaucoup d&#8217;\u0153ufs, c&#8217;est le secret de Sol\u00e8ne pour une p\u00e2te \u00e0 cr\u00eapes r\u00e9ussie.<\/strong><\/p>\n[4:13] &#8211; Sol\u00e8ne<br \/>\n<strong>Et bien s\u00fbr, apr\u00e8s, faut la laisser reposer une nuit, c&#8217;est tr\u00e8s bien, \u00e7a fait plein de petites bulles dessus et c&#8217;est meilleur.<\/strong><\/p>\n[4:19] &#8211; Animatrice<br \/>\n<strong>Le mot cr\u00eape, du latin crispus, signifie fris\u00e9 ou cr\u00e9pu, car justement la p\u00e2te ondule \u00e0 la cuisson. Elle est apparue en Bretagne au XIII\u1d49 si\u00e8cle avec l&#8217;introduction du sarrasin. Rapport\u00e9 des croisades en Asie, la plante c&#8217;est tr\u00e8s bien acclimat\u00e9e \u00e0 la r\u00e9gion, mais des cr\u00eapes, on en retrouve partout dans le monde.<\/strong><\/p>\n[4:39] &#8211; Orateur 1<br \/>\n<strong>Penser syst\u00e9matiquement en Bretagne quand on parle de cr\u00eapes, c&#8217;est une erreur. Mais bon, en m\u00eame temps, c&#8217;est nous qui savons bien les faire &#8230;<\/strong><\/p>\n[4:47] &#8211; Rolande<br \/>\n<strong>C&#8217;\u00e9tait quand m\u00eame le plat du pauvre. Alors qu&#8217;on met des produits trop riches, Je ne suis pas d&#8217;accord l\u00e0-dessus. Pour moi, une bonne cr\u00eape c&#8217;est avec peu d&#8217;\u00e9l\u00e9ments, mais de bons produits.<\/strong><\/p>\n[4:57] &#8211; Animatrice<br \/>\n<strong>Il ne faut pas grand-chose pour r\u00e9galer toute la famille avec des cr\u00eapes au sucre. 250 grammes de farine, si \u00e7a c&#8217;est xxx, un demi-litre de lait et du sucre, tout \u00e7a accompagn\u00e9 d&#8217;un bon cidre. Olivier, notre \u00e9picier breton, pr\u00e9conise un demi-sec. La diff\u00e9rence entre les cidres, ce sont les degr\u00e9s d&#8217;alcool.<\/strong><\/p>\n[5:18] &#8211; Olivier<br \/>\n<strong>Et \u00e7a peut aller jusqu&#8217;\u00e0 huit, neuf, voire beaucoup plus si c&#8217;est un vieux cidre, parce que le cidre continue \u00e0 fermenter, m\u00eame mis en bouteille. C&#8217;est pour \u00e7a d&#8217;ailleurs qu&#8217;on conseille aux gens de boire des cidres de l&#8217;ann\u00e9e et du cidre breton de surcro\u00eet quoi. Voil\u00e0. Parce que c&#8217;est le meilleur, tout le monde le sait.<\/strong><\/p>\n[5:34] &#8211; Animatrice<br \/>\n<strong>Le meilleur cidre, la m\u00e9t\u00e9o la plus contrast\u00e9e, la plus belle terre. C&#8217;est s\u00fbr que nos Bretons d\u00e9fendent avec conviction et un certain humour leur Bretagne, car Chandeleur ou pas, leur r\u00e9gion, ils la vivent tous les jours.<\/strong><\/p>\n[5:48] &#8211; Olivier<br \/>\n<strong>Et un sentiment d&#8217;appartenance tr\u00e8s fort de partir leur territoire. A la maison de mon p\u00e8re avec sa m\u00e8re, je l&#8217;ai toujours vu parler en breton. \u00c7a fait partie de notre histoire.<\/strong><\/p>\n[5:58] &#8211; Sol\u00e8ne<br \/>\n<strong>Il y a quelque chose de tr\u00e8s fort chez les Bretons. Moi, mes enfants, le papa, il est pas breton, mais je dis vous \u00eates breton et il est pas fran\u00e7ais non plus. Mais j&#8217;ai dit vous \u00eates breton, j&#8217;ai dit que vous \u00eates breton avant tout.<\/strong><\/p>\n[6:09] &#8211; Fran\u00e7oise<br \/>\n<strong>\u00c7a a \u00e9t\u00e9 justement la force de la Bretagne de savoir parfois d\u00e9passer ce c\u00f4t\u00e9 bout du monde pour aller vers l&#8217;ext\u00e9rieur, vers les gens, vers d&#8217;autres pays, vers l&#8217;avenir, en r\u00e9alit\u00e9.<\/strong><\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><a title=\"View on YouTube\" href=\"https:\/\/youtu.be\/Gh5J9posBYY\" target=\"_default\" rel=\"noopener\"> View on YouTube<\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>[0:04] &#8211; Animatrice Qui de mieux que les Bretons pour nous raconter l&#8217;incroyable histoire de la Chandeleur ? [0:09] &#8211; Fran\u00e7oise Moi, je viens du Morbihan, moi je suis originaire de la presqu&#8217;\u00eele de Rhuys. [0:15] &#8211; Rolande Moi je&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"https:\/\/saint-christophers-hosting.com\/index.php\/2023\/02\/07\/la-chandeleur\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":3149,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-3147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-french"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2023\/02\/laChandeleur.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8rlea-OL","_links":{"self":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/3147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/comments?post=3147"}],"version-history":[{"count":5,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/3147\/revisions"}],"predecessor-version":[{"id":3222,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/3147\/revisions\/3222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/media\/3149"}],"wp:attachment":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/media?parent=3147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/categories?post=3147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/tags?post=3147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}