{"id":2417,"date":"2022-03-21T11:45:47","date_gmt":"2022-03-21T11:45:47","guid":{"rendered":"https:\/\/saint-christophers-hosting.com\/?p=2417"},"modified":"2022-03-21T11:45:47","modified_gmt":"2022-03-21T11:45:47","slug":"la-fenetre","status":"publish","type":"post","link":"https:\/\/saint-christophers-hosting.com\/index.php\/2022\/03\/21\/la-fenetre\/","title":{"rendered":"La fen\u00eatre"},"content":{"rendered":"<p>La fen\u00eatre<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-2417-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2022\/03\/LaFenetreDeGuyDeMaupassant.mp3?_=1\" \/><a href=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2022\/03\/LaFenetreDeGuyDeMaupassant.mp3\">https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2022\/03\/LaFenetreDeGuyDeMaupassant.mp3<\/a><\/audio>\n<p>Je fis la connaissance de Mme de Jadelle \u00e0 Paris, cet hiver. Elle me plut infiniment tout de suite. Vous la connaissez d&#8217;ailleurs autant que moi&#8230;, non&#8230; pardon&#8230; presque autant que moi&#8230; Vous savez comme elle est fantasque<a href=\"#_edn1\" name=\"_ednref1\">[1]<\/a> et po\u00e9tique en m\u00eame temps. Libre d&#8217;allures et de c\u0153ur impressionnable, volontaire, \u00e9mancip\u00e9e, hardie<a href=\"#_edn2\" name=\"_ednref2\">[2]<\/a>, entreprenante, audacieuse, enfin au-dessus de tout pr\u00e9jug\u00e9<a href=\"#_edn3\" name=\"_ednref3\">[3]<\/a>, et, malgr\u00e9 cela, sentimentale, d\u00e9licate, vite froiss\u00e9e<a href=\"#_edn4\" name=\"_ednref4\">[4]<\/a>, tendre et pudique<a href=\"#_edn5\" name=\"_ednref5\">[5]<\/a>.<\/p>\n<p>Elle \u00e9tait veuve, j&#8217;adore les veuves, par paresse. Je cherchais alors \u00e0 me marier, je lui fis la cour<a href=\"#_edn6\" name=\"_ednref6\">[6]<\/a>. Plus je la connaissais, plus elle me plaisait ; et je crus le moment venu de risquer ma demande. J&#8217;\u00e9tais amoureux d&#8217;elle et j&#8217;allais le devenir trop<a href=\"#_edn7\" name=\"_ednref7\">[7]<\/a>. Quand on se marie, il ne faut pas trop aimer sa femme, parce qu&#8217;alors on fait des b\u00eatises ; on se trouble, on devient en m\u00eame temps niais<a href=\"#_edn8\" name=\"_ednref8\">[8]<\/a> et brutal. Il faut se dominer encore. Si on perd la t\u00eate le premier soir, on risque fort de l&#8217;avoir bois\u00e9e<a href=\"#_edn9\" name=\"_ednref9\">[9]<\/a> un an plus tard.<\/p>\n<p>Donc, un jour, je me pr\u00e9sentai chez elle avec des gants clairs et je lui dis :<\/p>\n<p>\u2015 Madame, j&#8217;ai le bonheur de vous aimer et je viens vous demander si je puis avoir quelque espoir de vous plaire, en y mettant tous mes soins, et de vous donner mon nom.<\/p>\n<p>Elle me r\u00e9pondit tranquillement :<\/p>\n<p>\u2015 Comme vous y allez, monsieur ! J&#8217;ignore absolument si vous me plairez t\u00f4t ou tard ; mais je ne demande pas mieux que d&#8217;en faire l&#8217;\u00e9preuve.\u00a0 Comme homme, je ne vous trouve pas mal. Reste \u00e0 savoir ce que vous \u00eates comme c\u0153ur, comme caract\u00e8re et comme habitudes. La plupart des mariages deviennent orageux ou criminels, parce qu&#8217;on ne se conna\u00eet pas assez en s&#8217;accouplant<a href=\"#_edn10\" name=\"_ednref10\">[10]<\/a>. Il suffit d&#8217;un rien, d&#8217;une manie enracin\u00e9e<a href=\"#_edn11\" name=\"_ednref11\">[11]<\/a>, d&#8217;une opinion tenace sur un point quelconque de morale, de religion ou de n&#8217;importe quoi, d&#8217;un geste qui d\u00e9pla\u00eet, d&#8217;un tic<a href=\"#_edn12\" name=\"_ednref12\">[12]<\/a>, d&#8217;un tout petit d\u00e9faut ou m\u00eame d&#8217;une qualit\u00e9 d\u00e9sagr\u00e9able pour faire deux ennemis irr\u00e9conciliables, acharn\u00e9s<a href=\"#_edn13\" name=\"_ednref13\">[13]<\/a> et encha\u00een\u00e9s l&#8217;un \u00e0 l&#8217;autre jusqu&#8217;\u00e0 la mort, des deux fianc\u00e9s les plus tendres et les plus passionn\u00e9s.<\/p>\n<p>Je ne me marierai pas, monsieur, sans conna\u00eetre \u00e0 fond, dans les coins et replis de l&#8217;\u00e2me, l&#8217;homme dont je partagerai l&#8217;existence. Je le veux \u00e9tudier \u00e0 loisir, de tout pr\u00e8s, pendant des mois.<\/p>\n<p>Voici donc ce que je vous propose. Vous allez venir passer l&#8217;\u00e9t\u00e9 chez moi, dans ma propri\u00e9t\u00e9 de Lauville, et nous verrons l\u00e0, tranquillement, si nous sommes faits pour vivre c\u00f4te \u00e0 c\u00f4te&#8230;<\/p>\n<p>Je vous vois rire ! Vous avez une mauvaise pens\u00e9e. Oh ! monsieur, si je n&#8217;\u00e9tais pas s\u00fbre de moi, je ne vous ferais point cette proposition. J&#8217;ai pour l&#8217;amour, tel que vous le comprenez, vous autres hommes, un tel m\u00e9pris<a href=\"#_edn14\" name=\"_ednref14\">[14]<\/a> et un tel d\u00e9go\u00fbt qu&#8217;une chute est impossible pour moi. Acceptez-vous ?<\/p>\n<p>Je lui baisai la main.<\/p>\n<p>\u2015 Quand partons-nous, madame ?<\/p>\n<p>\u2015 Le 10 mai. C&#8217;est entendu ?<\/p>\n<p>\u2015 C&#8217;est entendu.<\/p>\n<p>Un mois plus tard, je m&#8217;installais chez elle. C&#8217;\u00e9tait vraiment une singuli\u00e8re femme. Du matin au soir elle m&#8217;\u00e9tudiait. Comme elle adore les chevaux, nous passions chaque jour des heures \u00e0 nous promener par les bois, en parlant de tout, car elle cherchait \u00e0 p\u00e9n\u00e9trer mes plus intimes pens\u00e9es autant qu&#8217;elle s&#8217;effor\u00e7ait d&#8217;observer jusqu&#8217;\u00e0 mes moindres mouvements.<\/p>\n<p>Quant \u00e0 moi, je devenais follement amoureux et je ne m&#8217;inqui\u00e9tais nullement de l&#8217;accord de nos caract\u00e8res. Je m&#8217;aper\u00e7us bient\u00f4t que mon sommeil lui-m\u00eame \u00e9tait soumis \u00e0 une surveillance. Quelqu&#8217;un couchait dans une petite chambre \u00e0 c\u00f4t\u00e9 de la mienne, o\u00f9 l&#8217;on n&#8217;entrait que fort tard et avec des pr\u00e9cautions infinies. Cet espionnage de tous les instants finit par m&#8217;impatienter. Je voulus h\u00e2ter le d\u00e9nouement, et je devins, un soir, entreprenant. Elle me re\u00e7ut de telle fa\u00e7on que je m&#8217;abstins de toute tentative nouvelle ; mais un violent d\u00e9sir m&#8217;envahit de lui faire payer, d&#8217;une fa\u00e7on quelconque, le r\u00e9gime policier auquel j&#8217;\u00e9tais soumis, et je m&#8217;avisai d&#8217;un moyen.<\/p>\n<p>Vous connaissez C\u00e9sarine, sa femme de chambre, une jolie fille de Granville, o\u00f9 toutes les femmes sont belles, mais aussi blonde que sa ma\u00eetresse est brune.<\/p>\n<p>Donc un apr\u00e8s-midi j&#8217;attirai<a href=\"#_edn15\" name=\"_ednref15\">[15]<\/a> la soubrette dans ma chambre, je lui mis cent francs dans la main et je lui dis :<\/p>\n<p>\u2015 Ma ch\u00e8re enfant, je ne veux te demander rien de vilain, mais je d\u00e9sire faire envers ta ma\u00eetresse ce qu&#8217;elle fait envers moi.<\/p>\n<p>La petite bonne souriait d&#8217;un air sournois<a href=\"#_edn16\" name=\"_ednref16\">[16]<\/a>. Je repris.<\/p>\n<p>\u2015 On me surveille jour et nuit, je le sais. On me regarde manger, boire, m&#8217;habiller, me raser et mettre mes chaussettes, je le sais.<\/p>\n<p>La fillette articula :<\/p>\n<p>\u2015 Dame, monsieur&#8230;, puis se tut.<\/p>\n<p>Je continuai :<\/p>\n<p>\u2015 Tu couches dans la chambre \u00e0 c\u00f4t\u00e9 pour \u00e9couter si je souffle<a href=\"#_edn17\" name=\"_ednref17\">[17]<\/a> ou si je r\u00eave tout haut<a href=\"#_edn18\" name=\"_ednref18\">[18]<\/a>, ne le nie pas !&#8230;<\/p>\n<p>Elle se mit \u00e0 rire tout \u00e0 fait et pronon\u00e7a :<\/p>\n<p>\u2015 Dame, monsieur&#8230;, puis se tut encore.<\/p>\n<p>Je m&#8217;animai :<\/p>\n<p>\u2015 Eh bien, tu comprends, ma fille, qu&#8217;il n&#8217;est pas juste qu&#8217;on sache tout sur mon compte et que je ne sache rien sur celui de la personne qui sera ma femme. Je l&#8217;aime de toute mon \u00e2me. Elle a le visage, le c\u0153ur, l&#8217;esprit que je r\u00eavais, je suis le plus heureux des hommes sous ce rapport ; cependant il y a des choses que je voudrais bien savoir&#8230;<\/p>\n<p>C\u00e9sarine se d\u00e9cida \u00e0 enfoncer dans sa poche mon billet de banque. Je compris que le march\u00e9 \u00e9tait conclu.<\/p>\n<p>\u2015 Ecoute, ma fille, nous autres hommes, nous tenons beaucoup \u00e0 certains&#8230; \u00e0 certains&#8230; d\u00e9tails&#8230; physiques, qui n&#8217;emp\u00eachent pas une femme d&#8217;\u00eatre charmante, mais qui peuvent changer son prix \u00e0 nos yeux. Je ne te demande pas de me dire du mal de ta ma\u00eetresse, ni m\u00eame de m&#8217;avouer<a href=\"#_edn19\" name=\"_ednref19\">[19]<\/a> ses d\u00e9fauts secrets si elle en a. R\u00e9pond seulement avec franchise<a href=\"#_edn20\" name=\"_ednref20\">[20]<\/a> aux quatre ou cinq questions que je vais te poser. Tu connais Mme de Jadelle comme toi-m\u00eame, puisque tu l&#8217;habilles et que tu la d\u00e9shabilles tous les jours. Eh bien, voyons, dis-moi cela. Est-elle aussi grasse qu&#8217;elle en a l&#8217;air ?<\/p>\n<p>La petite bonne ne r\u00e9pondit pas.<\/p>\n<p>Je repris :<\/p>\n<p>\u2015 Voyons, mon enfant, tu n&#8217;ignores pas qu&#8217;il y a des femmes qui se mettent du coton, tu sais, du coton l\u00e0 o\u00f9, l\u00e0 o\u00f9&#8230; enfin du coton l\u00e0 o\u00f9 on nourrit les petits enfants, et aussi l\u00e0 o\u00f9 on s&#8217;assoit. Dis-moi, met-elle du coton ?<\/p>\n<p>C\u00e9sarine avait baiss\u00e9 les yeux. Elle pronon\u00e7a timidement :<\/p>\n<p>\u2015 Demandez toujours, monsieur, je r\u00e9pondrai tout \u00e0 la fois.<\/p>\n<p>\u2015 Eh bien, ma fille, il y a aussi des femmes qui ont les genoux rentr\u00e9s, si bien qu&#8217;ils s&#8217;entre-frottent<a href=\"#_edn21\" name=\"_ednref21\">[21]<\/a> \u00e0 chaque pas qu&#8217;elles font. Il y en a d&#8217;autres qui les ont \u00e9cart\u00e9s, ce qui leur fait des jambes pareilles aux arches d&#8217;un pont. On voit le paysage au milieu. C&#8217;est tr\u00e8s joli des deux fa\u00e7ons. Dis-moi comment sont les jambes de ta ma\u00eetresse ?<\/p>\n<p>La petite bonne ne r\u00e9pondit pas.<\/p>\n<p>Je continuai :<\/p>\n<p>\u2015 Il y en a qui ont la poitrine si belle qu&#8217;elle forme un gros pli dessous. Il y en a qui ont des gros bras avec une taille mince. Il y en a qui sont tr\u00e8s fortes par devant et pas du tout par derri\u00e8re ; d&#8217;autres qui sont tr\u00e8s fortes par derri\u00e8re et pas du tout par devant. Tout cela est tr\u00e8s joli, tr\u00e8s joli ; mais je voudrais bien savoir comment est faite ta ma\u00eetresse. Dis-le-moi franchement et je te donnerai encore beaucoup d&#8217;argent&#8230;<\/p>\n<p>C\u00e9sarine me regarda au fond des yeux et r\u00e9pondit en riant de tout son c\u0153ur :<\/p>\n<p>\u2015 Monsieur, \u00e0 part qu&#8217;elle est noire<a href=\"#_edn22\" name=\"_ednref22\">[22]<\/a>, madame est faite tout comme moi.<\/p>\n<p>Puis elle s&#8217;enfuit.<\/p>\n<p>J&#8217;\u00e9tais jou\u00e9<a href=\"#_edn23\" name=\"_ednref23\">[23]<\/a>. Cette fois je me trouvai ridicule et je r\u00e9solus de me venger au moins de cette bonne impertinente.<\/p>\n<p>Une heure plus tard, j&#8217;entrai avec pr\u00e9caution dans la petite chambre, d&#8217;o\u00f9 elle m&#8217;\u00e9coutait dormir, et je d\u00e9vissai les verrous<a href=\"#_edn24\" name=\"_ednref24\">[24]<\/a>.<\/p>\n<p>Elle arriva vers minuit \u00e0 son poste d&#8217;observation. Je la suivis aussit\u00f4t. En m&#8217;apercevant, elle voulut crier ; mais je lui fermai la bouche avec ma main et je me convainquis, sans trop d&#8217;efforts, que, si elle n&#8217;avait pas menti, Mme de Jadelle devait \u00eatre tr\u00e8s bien faite.<\/p>\n<p>Je pris m\u00eame grand go\u00fbt \u00e0 cette constatation, qui, d&#8217;ailleurs, pouss\u00e9e un peu loin, ne semblait plus d\u00e9plaire \u00e0 C\u00e9sarine.<\/p>\n<p>C&#8217;\u00e9tait, ma foi, un ravissant \u00e9chantillon<a href=\"#_edn25\" name=\"_ednref25\">[25]<\/a> de la race bas-normande, forte et fine en m\u00eame temps. Il lui manquait peut-\u00eatre certaines d\u00e9licatesses de soins qu&#8217;aurait m\u00e9pris\u00e9es Henri IV. Je les lui r\u00e9v\u00e9lai bien vite, et comme j&#8217;adore les parfums, je lui fis cadeau, le soir m\u00eame, d&#8217;un flacon de lavande ambr\u00e9e<a href=\"#_edn26\" name=\"_ednref26\">[26]<\/a>.<\/p>\n<p>Nous f\u00fbmes bient\u00f4t plus li\u00e9s m\u00eame que je n&#8217;aurais cru, presque amis.<\/p>\n<p>Elle devint une ma\u00eetresse exquise, naturellement spirituelle, et rou\u00e9e \u00e0 plaisir<a href=\"#_edn27\" name=\"_ednref27\">[27]<\/a>. C&#8217;e\u00fbt \u00e9t\u00e9, \u00e0 Paris, une courtisane de grand m\u00e9rite.<\/p>\n<p>Les douceurs qu&#8217;elle me procura me permirent d&#8217;attendre sans impatience la fin de l&#8217;\u00e9preuve de Mme de Jadelle. Je devins d&#8217;un caract\u00e8re incomparable, souple, docile, complaisant.<\/p>\n<p>Quant \u00e0 ma fianc\u00e9e, elle me trouvait sans doute d\u00e9licieux, et je compris, \u00e0 certains signes, que j&#8217;allais bient\u00f4t \u00eatre agr\u00e9\u00e9. J&#8217;\u00e9tais certes le plus heureux des hommes du monde, attendant tranquillement le baiser l\u00e9gal d&#8217;une femme que j&#8217;aimais dans les bras d&#8217;une jeune et belle fille pour qui j&#8217;avais de la tendresse.<\/p>\n<p>C&#8217;est ici, madame, qu&#8217;il faut vous tourner un peu ; j&#8217;arrive \u00e0 l&#8217;endroit d\u00e9licat.<\/p>\n<p>Mme de Jadelle, un soir, comme nous revenions de notre promenade \u00e0 cheval, se plaignit vivement que ses palefreniers<a href=\"#_edn28\" name=\"_ednref28\">[28]<\/a> n&#8217;eussent point pour la b\u00eate qu&#8217;elle montait certaines pr\u00e9cautions exig\u00e9es par elle. Elle r\u00e9p\u00e9ta m\u00eame plusieurs fois :<\/p>\n<p>\u2015 Qu&#8217;ils prennent garde, qu&#8217;ils prennent garde, j&#8217;ai un moyen de les surprendre.<\/p>\n<p>Je passai une nuit calme, dans mon lit. Je m&#8217;\u00e9veillai t\u00f4t, plein d&#8217;ardeur et d&#8217;entrain. Et je m&#8217;habillai.<\/p>\n<p>J&#8217;avais l&#8217;habitude d&#8217;aller chaque matin fumer une cigarette sur une tourelle du ch\u00e2teau o\u00f9 montait un escalier en lima\u00e7on<a href=\"#_edn29\" name=\"_ednref29\">[29]<\/a>, \u00e9clair\u00e9 par une grande fen\u00eatre \u00e0 la hauteur du premier \u00e9tage. Je m&#8217;avan\u00e7ais sans bruit, les pieds en mes pantoufles de maroquin aux semelles ouat\u00e9es<a href=\"#_edn30\" name=\"_ednref30\">[30]<\/a>, pour gravir les premi\u00e8res marches, quand j&#8217;aper\u00e7us C\u00e9sarine, pench\u00e9e \u00e0 la fen\u00eatre, regardant au dehors.<\/p>\n<p>Je n&#8217;aper\u00e7us pas C\u00e9sarine tout enti\u00e8re, mais seulement une moiti\u00e9 de C\u00e9sarine, la seconde moiti\u00e9 d&#8217;elle ; j&#8217;aimais autant cette moiti\u00e9-l\u00e0. De Mme de Jadelle j&#8217;eusse pr\u00e9f\u00e9r\u00e9 peut-\u00eatre la premi\u00e8re. Elle \u00e9tait charmante ainsi, si ronde, v\u00eatue \u00e0 peine d&#8217;un petit jupon blanc, cette moiti\u00e9 qui s&#8217;offrait \u00e0 moi.<\/p>\n<p>Je m&#8217;approchai si doucement que la jeune fille n&#8217;entendit rien. Je me mis \u00e0 genoux ; je pris avec mille pr\u00e9cautions les deux bords du fin jupon, et, brusquement, je relevai. Je la reconnus aussit\u00f4t, pleine, fra\u00eeche, grasse et douce, la face secr\u00e8te de ma ma\u00eetresse, et j&#8217;y jetai, pardon, madame, j&#8217;y jetai un tendre baiser<a href=\"#_edn31\" name=\"_ednref31\">[31]<\/a>, un baiser d&#8217;amant qui peut tout oser.<\/p>\n<p>Je fus surpris. Cela sentait la verveine<a href=\"#_edn32\" name=\"_ednref32\">[32]<\/a> ! Mais je n&#8217;eus pas le temps d&#8217;y r\u00e9fl\u00e9chir. Je re\u00e7us un grand coup ou plut\u00f4t une pouss\u00e9e dans la figure qui faillit me briser le nez. J&#8217;entendis un cri qui me fit dresser les cheveux<a href=\"#_edn33\" name=\"_ednref33\">[33]<\/a>. La personne s&#8217;\u00e9tait retourn\u00e9e \u2015 c&#8217;\u00e9tait Mme de Jadelle !<\/p>\n<p>Elle battit l&#8217;air de ses mains comme une femme qui perd connaissance ; elle haleta quelques secondes, fit le geste de me cravacher, puis s&#8217;enfuit.<\/p>\n<p>Dix minutes plus tard, C\u00e9sarine, stup\u00e9faite, m&#8217;apportait une lettre ; je lus :<\/p>\n<p>\u00ab Mme de Jadelle esp\u00e8re que M. de Brives la d\u00e9barrassera imm\u00e9diatement de sa pr\u00e9sence. \u00bb<\/p>\n<p>Je partis.<\/p>\n<p>Eh bien, je ne suis point encore consol\u00e9. J&#8217;ai tent\u00e9 de tous les moyens et de toutes les explications pour me faire pardonner cette m\u00e9prise. Toutes mes d\u00e9marches ont \u00e9chou\u00e9. Depuis ce moment, voyez-vous, j&#8217;ai dans&#8230; dans le c\u0153ur un go\u00fbt de verveine qui me donne un d\u00e9sir immod\u00e9r\u00e9 de sentir encore ce bouquet-l\u00e0.<\/p>\n<p><a href=\"#_ednref1\" name=\"_edn1\">[1]<\/a> Fantasque &#8211; whimsical<\/p>\n<p><a href=\"#_ednref2\" name=\"_edn2\">[2]<\/a> Hardie &#8211; bold<\/p>\n<p><a href=\"#_ednref3\" name=\"_edn3\">[3]<\/a> Pr\u00e9jug\u00e9 &#8211; prejudice<\/p>\n<p><a href=\"#_ednref4\" name=\"_edn4\">[4]<\/a> Froiss\u00e9e &#8211; hurt<\/p>\n<p><a href=\"#_ednref5\" name=\"_edn5\">[5]<\/a> Pudique &#8211; modest<\/p>\n<p><a href=\"#_ednref6\" name=\"_edn6\">[6]<\/a> Je lui fis la cour \u2013 I courted her<\/p>\n<p><a href=\"#_ednref7\" name=\"_edn7\">[7]<\/a> J&#8217;allais le devenir trop \u2013 it was getting to be too much<\/p>\n<p><a href=\"#_ednref8\" name=\"_edn8\">[8]<\/a> Niais &#8211; stupid<\/p>\n<p><a href=\"#_ednref9\" name=\"_edn9\">[9]<\/a> L&#8217;avoir bois\u00e9e \u2013 to have it broken<\/p>\n<p><a href=\"#_ednref10\" name=\"_edn10\">[10]<\/a> S&#8217;accoupler \u2013 to couple<\/p>\n<p><a href=\"#_ednref11\" name=\"_edn11\">[11]<\/a> Une manie enracin\u00e9e \u2013 ingrained manner<\/p>\n<p><a href=\"#_ednref12\" name=\"_edn12\">[12]<\/a> Un tic \u2013 a tic<\/p>\n<p><a href=\"#_ednref13\" name=\"_edn13\">[13]<\/a> Acharn\u00e9s &#8211; fierce<\/p>\n<p><a href=\"#_ednref14\" name=\"_edn14\">[14]<\/a> M\u00e9pris &#8211; contempt<\/p>\n<p><a href=\"#_ednref15\" name=\"_edn15\">[15]<\/a> j&#8217;attirai \u2013 I lured<\/p>\n<p><a href=\"#_ednref16\" name=\"_edn16\">[16]<\/a> Sournois &#8211; slyly<\/p>\n<p><a href=\"#_ednref17\" name=\"_edn17\">[17]<\/a> Souffler \u2013 to whistle, to snore<\/p>\n<p><a href=\"#_ednref18\" name=\"_edn18\">[18]<\/a> Je r\u00eave tout haut \u2013 I talk in my dreams<\/p>\n<p><a href=\"#_ednref19\" name=\"_edn19\">[19]<\/a> Avouer \u2013 to confess<\/p>\n<p><a href=\"#_ednref20\" name=\"_edn20\">[20]<\/a> Avec franchise &#8211; flankly<\/p>\n<p><a href=\"#_ednref21\" name=\"_edn21\">[21]<\/a> S&#8217;entre-frotter \u2013 to rub together<\/p>\n<p><a href=\"#_ednref22\" name=\"_edn22\">[22]<\/a> \u00c0 part qu&#8217;elle est noire \u2013 except that she has black hair<\/p>\n<p><a href=\"#_ednref23\" name=\"_edn23\">[23]<\/a> J&#8217;\u00e9tais jou\u00e9 \u2013 I had lost my bet<\/p>\n<p><a href=\"#_ednref24\" name=\"_edn24\">[24]<\/a> Je d\u00e9vissai les verrous \u2013 I opened the locks<\/p>\n<p><a href=\"#_ednref25\" name=\"_edn25\">[25]<\/a> Echantillon \u2013 an example<\/p>\n<p><a href=\"#_ednref26\" name=\"_edn26\">[26]<\/a> Ambr\u00e9e &#8211; amber<\/p>\n<p><a href=\"#_ednref27\" name=\"_edn27\">[27]<\/a> Rou\u00e9e \u00e0 plaisir \u2013 addicted to pleasure<\/p>\n<p><a href=\"#_ednref28\" name=\"_edn28\">[28]<\/a> Palefreniers &#8211; grooms<\/p>\n<p><a href=\"#_ednref29\" name=\"_edn29\">[29]<\/a> Lima\u00e7on &#8211; spiral<\/p>\n<p><a href=\"#_ednref30\" name=\"_edn30\">[30]<\/a> Semelles ouat\u00e9es \u2013 padded soles<\/p>\n<p><a href=\"#_ednref31\" name=\"_edn31\">[31]<\/a> Jeter tendre baiser \u2013 to blow a kiss<\/p>\n<p><a href=\"#_ednref32\" name=\"_edn32\">[32]<\/a> Verveine &#8211; verbena<\/p>\n<p><a href=\"#_ednref33\" name=\"_edn33\">[33]<\/a> J&#8217;entendis un cri qui me fit dresser les cheveux \u2013 I heard a cry which made my hair stand on end<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La fen\u00eatre Je fis la connaissance de Mme de Jadelle \u00e0 Paris, cet hiver. Elle me plut infiniment tout de suite. Vous la connaissez d&#8217;ailleurs autant que moi&#8230;, non&#8230; pardon&#8230; presque autant que moi&#8230; Vous savez comme elle est fantasque[1]&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"https:\/\/saint-christophers-hosting.com\/index.php\/2022\/03\/21\/la-fenetre\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2416,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-2417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-french"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2022\/03\/GuyDeMaupassant-02.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8rlea-CZ","_links":{"self":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/2417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/comments?post=2417"}],"version-history":[{"count":2,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/2417\/revisions"}],"predecessor-version":[{"id":2420,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/2417\/revisions\/2420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/media\/2416"}],"wp:attachment":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/media?parent=2417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/categories?post=2417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/tags?post=2417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}