{"id":2365,"date":"2022-02-02T11:04:27","date_gmt":"2022-02-02T11:04:27","guid":{"rendered":"https:\/\/saint-christophers-hosting.com\/?p=2365"},"modified":"2022-03-30T17:45:37","modified_gmt":"2022-03-30T16:45:37","slug":"asterix-et-obelix","status":"publish","type":"post","link":"https:\/\/saint-christophers-hosting.com\/index.php\/2022\/02\/02\/asterix-et-obelix\/","title":{"rendered":"Asterix et Obelix"},"content":{"rendered":"<p><a href=\"https:\/\/www.arte.tv\/fr\/videos\/094490-024-A\/tout-est-vrai-ou-presque\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.arte.tv\/fr\/videos\/094490-024-A\/tout-est-vrai-ou-presque\/<\/a><\/p>\n<p><a href=\"\/wp-content\/uploads\/2022\/02\/Asterix1.png\"><img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"2366\" data-permalink=\"https:\/\/saint-christophers-hosting.com\/index.php\/2022\/02\/02\/asterix-et-obelix\/asterix1\/\" data-orig-file=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2022\/02\/Asterix1.png\" data-orig-size=\"318,287\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Asterix1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2022\/02\/Asterix1.png\" class=\"size-full wp-image-2366 alignnone\" src=\"\/wp-content\/uploads\/2022\/02\/Asterix1.png\" alt=\"\" width=\"318\" height=\"287\" srcset=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2022\/02\/Asterix1.png 318w, https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2022\/02\/Asterix1-300x271.png 300w\" sizes=\"(max-width: 318px) 100vw, 318px\" \/><\/a><\/p>\n[00:00]\nCes grands voyageurs parlent 111 langues et ont visit\u00e9 le monde entier avec pour seul bagage, un menhir. D&#8217;ailleurs, avec tous les albums qu&#8217;ils ont vendus, \u00e7a, on pourrait faire deux fois le tour de la terre tranquille. Aujourd&#8217;hui, Ast\u00e9rix et Ob\u00e9lix.<\/p>\n[00:28]\nAst\u00e9rix et Ob\u00e9lix naissent en une apr\u00e8s-midi midi d&#8217;ao\u00fbt 1959, lors d&#8217;une discussion enflamm\u00e9e entre le dessinateur Albert Uderzo et le sc\u00e9nariste Ren\u00e9 Goscinny, aid\u00e9s par quelques verres de pastis et beaucoup de cigarettes, repense \u00e0 leur le\u00e7on d&#8217;histoire de France et au duo Laurel et Hardy. Ils inventent alors deux h\u00e9ros gaulois. L&#8217;un est petit et rus\u00e9, l&#8217;autre grand et costaud. Ils vivent au temps de C\u00e9sar, en Bretagne. C&#8217;est le seul bord de mer que conna\u00eet Uderzo et une potion magique les rend invincibles. Ces Gaulois n&#8217;ont qu&#8217;une peur que le ciel leur tombe sur la t\u00eate. Goscinny et Uderzo sont soulag\u00e9s parce qu&#8217;en fait, ils sont tr\u00e8s en retard. Ils doivent trouver un h\u00e9ros fran\u00e7ais pour un nouveau journal qui veut se diff\u00e9rencier de la concurrence belge et am\u00e9ricaine. Ils ont d&#8217;abord adapt\u00e9 le classique Roman de Renart en b\u00e9d\u00e9.<\/p>\n[01:15]\nAst\u00e9rix le Gaulois trouve sa place dans le num\u00e9ro un de pilote, en octobre 59. En 1961, le premier album d&#8217;Ast\u00e9rix et Ob\u00e9lix a un tirage modeste de 6.000 exemplaires. Mais leur lectorat prend de l&#8217;ampleur en m\u00eame temps que leurs aventures. Nos h\u00e9ros ne font pas que les Romains, ils parcourent le monde et \u00e0 chaque fois, les histoires jouent avec des clich\u00e9s, comme dans Ast\u00e9rix que sont les Goths en 63, o\u00f9 la population est d\u00e9crite comme tr\u00e8s organis\u00e9e et militariste. Mais \u00e7a pla\u00eet puisque la traduction allemande de 70 est un succ\u00e8s. Avec son humour \u00e0 double lecture, la s\u00e9rie Ast\u00e9rix, qui permet \u00e0 la bande dessin\u00e9e de ne plus \u00eatre consid\u00e9r\u00e9e comme un passetemps compte. En France, en 66, le tr\u00e8s s\u00e9rieux hebdomadaire L&#8217;Express consacre sa une au ph\u00e9nom\u00e8ne. Les albums sont tir\u00e9s \u00e0 plus d&#8217;un million d&#8217;exemplaires. Ast\u00e9rix et Ob\u00e9lix sont tellement populaires qu&#8217;ils sont adapt\u00e9s aux films d&#8217;animation.<\/p>\n[02:14]\nD\u00e9\u00e7u par le r\u00e9sultat, ceci r\u00e9alise le suivant Ast\u00e9rix et Cl\u00e9op\u00e2tre en 68. Et en 99, les acteurs Christian Clavier et G\u00e9rard Depardieu interpr\u00e8tent les h\u00e9ros gaulois dans un film en prises de vues r\u00e9elles de Claude Zidi s&#8217;y croirait. Trois ans plus tard, Mission Cl\u00e9op\u00e2tre, r\u00e9alis\u00e9 par Alain Chabat, enregistre 14,5 millions d&#8217;entr\u00e9es en France. Apr\u00e8s avoir pleur\u00e9 la mort de Ren\u00e9 Goscinny en 77, Uderzo cr\u00e9a la maison d&#8217;\u00e9dition Albert Ren\u00e9 et continue seul les albums. Malgr\u00e9 les doutes, le succ\u00e8s ne se d\u00e9ment pas. En 2013, handicap\u00e9 par des probl\u00e8mes d&#8217;arthrose, Uderzo passe le relais au dessinateur Didier Conrad et au sc\u00e9nariste Jean-Yves Ferri avant de dispara\u00eetre en 2020. Sans ces cr\u00e9ateurs, Ast\u00e9rix et Ob\u00e9lix continuent de cartonner. Et oui, ils sont tomb\u00e9s dans la marmite du succ\u00e8s. Uderzo \u00e9tait daltonien depuis qu&#8217;il avait colorier un cheval en vert. C&#8217;\u00e9tait son fr\u00e8re qui mettait en couleur.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/www.arte.tv\/fr\/videos\/094490-024-A\/tout-est-vrai-ou-presque\/ [00:00] Ces grands voyageurs parlent 111 langues et ont visit\u00e9 le monde entier avec pour seul bagage, un menhir. D&#8217;ailleurs, avec tous les albums qu&#8217;ils ont vendus, \u00e7a, on pourrait faire deux fois le tour de la terre tranquille.&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"https:\/\/saint-christophers-hosting.com\/index.php\/2022\/02\/02\/asterix-et-obelix\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":2366,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-2365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-french"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2022\/02\/Asterix1.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8rlea-C9","_links":{"self":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/2365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/comments?post=2365"}],"version-history":[{"count":5,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/2365\/revisions"}],"predecessor-version":[{"id":2495,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/2365\/revisions\/2495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/media\/2366"}],"wp:attachment":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/media?parent=2365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/categories?post=2365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/tags?post=2365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}