{"id":1247,"date":"2020-09-23T19:08:23","date_gmt":"2020-09-23T18:08:23","guid":{"rendered":"https:\/\/saint-christophers-hosting.com\/?p=1247"},"modified":"2020-09-26T13:59:12","modified_gmt":"2020-09-26T12:59:12","slug":"une-balade-le-long-du-canal","status":"publish","type":"post","link":"https:\/\/saint-christophers-hosting.com\/index.php\/2020\/09\/23\/une-balade-le-long-du-canal\/","title":{"rendered":"Une balade le long du canal"},"content":{"rendered":"<audio class=\"wp-audio-shortcode\" id=\"audio-1247-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2020\/09\/LeCanal-01.mp3?_=1\" \/><a href=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2020\/09\/LeCanal-01.mp3\">https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2020\/09\/LeCanal-01.mp3<\/a><\/audio>\n<p>Il y a un an, je me suis \u200b\u200bpromen\u00e9 le long du canal Kennet et Avon de Hungerford \u00e0 Newbury ; une semaine plus tard, j\u2019ai fait une balade de Hungerford \u00e0 Crofton Beam Engines. \u00a0Les trajets \u00e9taient tr\u00e8s agr\u00e9ables, reposants, int\u00e9ressants et gratuits. Un plan a \u00e9volu\u00e9 pour parcourir la longueur du canal entre la Tamise \u00e0 Reading et l&#8217;Avon \u00e0 Bath. La semaine derni\u00e8re, le projet s\u2019est termin\u00e9. [1, 2].<\/p>\n<p>Le canal construit au XVIIIe et au d\u00e9but du XIXe si\u00e8cle, a une histoire bien document\u00e9e. \u00a0Le canal relie Londres \u00e0 Bristol et une fois achev\u00e9 en 1810, c&#8217;\u00e9tait le M4 de son \u00e9poque. Lorsque la construction du chemin de fer a pris son envol en 1840, une ligne a \u00e9t\u00e9 construite le long du canal. \u00a0Aujourd&#8217;hui, les gares le long des 130 kilom\u00e8tres du canal sont au nombre de 17. Pas mal des gares se trouvent \u00e1 cote du canal. \u00a0Ainsi, traverser le canal petit \u00e0 petit et des trajets ferroviaires est une option viable.<\/p>\n<p>Mon parcours le long du canal s&#8217;est d\u00e9roul\u00e9 en neuf \u00e9tapes et sont indiqu\u00e9s dans le tableau. La plupart des journ\u00e9es commen\u00e7aient et se terminaient \u00e0 la gare de Hungerford et impliquaient un trajet vers le canal. \u00a0Les op\u00e9rateurs ferroviaires permettent aux passagers d&#8217;emporter un v\u00e9lo. Une moiti\u00e9 de la longueur du canal fait partie de la piste cyclable nationale num\u00e9ro 4 et le sentier est bien adapt\u00e9e aux v\u00e9los. Aucune gare \u00e0 Devizes, donc ma femme y a fait deux voyages, un pour me d\u00e9poser et un pour me r\u00e9cup\u00e9rer. [3].<\/p>\n<p>Le long du canal, nombreuses villes int\u00e9ressantes se trouvent, notamment Bath, Bradford-On-Avon, Devizes, Hungerford, Newbury et Reading. \u00a0Ces villes fournissent des services \u00e0 ceux qui traversent le canal en bateau. \u00a0Actuellement tout le trafic sur le canal est d\u00e9di\u00e9 au loisir, et les pubs, restaurants et d&#8217;autres commerces r\u00e9pondent aux besoins de ceux qui empruntent les bateaux du canal.<\/p>\n<p>En faisant la balade du canal, on a l&#8217;impression que le canal est ench\u00e2ss\u00e9 dans la campagne et qu&#8217;il en est ainsi depuis sa construction il y a 200 ans. Cependant, ce n\u2019est pas le cas. La derni\u00e8re utilisation commerciale du canal remonte \u00e0 1950 et en 1960, il \u00e9tait pratiquement abandonn\u00e9. Le canal a \u00e9t\u00e9 restaur\u00e9 par des b\u00e9n\u00e9voles de la Truste de Kennet and Avon Canal, \u00e0 partir de 1960 et enti\u00e8rement ouvert \u00e0 la circulation en 1990. \u00a0Depuis la r\u00e9ouverture, le canal a \u00e9t\u00e9 exploit\u00e9 et entretenu par la Truste, aid\u00e9e par des subventions de la Loterie Nationale.<\/p>\n<p>Pour ceux qui aiment regarder des documentaires de voyage, les acteurs Timothy West et Prunelle Scales ont r\u00e9alis\u00e9 de nombreuses s\u00e9ries d&#8217;\u00e9missions intitul\u00e9es \u00ab\u00a0Trajets Magnifiques du Canal\u00a0\u00bb ( &#8220;Great Canal Journeys&#8221;). La premi\u00e8re \u00e9mission, r\u00e9alis\u00e9e en 2014, les mettait en vedette sur le canal Kennet et Avon. Diffus\u00e9es sur Channel 4, les \u00e9missions sont disponibles encore \u00e0 la demande aupr\u00e8s des services de streaming. Timothy et Prunelle ont particip\u00e9 \u00e0 la restauration du canal et ont fait partie de la premi\u00e8re flottille de barges qui a travers\u00e9 le canal apr\u00e8s sa r\u00e9ouverture. [4].<\/p>\n<p>Pour moi, les quatre meilleurs emplacements le long du canal sont les aqueducs de Dundas et Avoncliff, la station de pompage de Crofton et les \u00e9cluses \u00e0 Caen Hill, pr\u00e8s de Devizes. \u00a0Les deux aqueducs portent le canal sur le fleuve Avon entre Bath et Bradford-On-Avon. \u00a0La station de pompage et ses moteurs \u00e0 vapeur de Crofton pompent de l&#8217;eau dans le canal \u00e0 son sommet. Les moteurs ont \u00e9t\u00e9 install\u00e9s en 1810 et fonctionnent encore aujourd&#8217;hui. \u00a0Les week-ends de vacances en \u00e9t\u00e9, les moteurs \u00e0 vapeur sont mis en marche et pompent de l&#8217;eau dans le canal. \u00a0Les 29 \u00e9cluses de Caen Hill pr\u00e8s de Devizes soul\u00e8vent les bateaux de la vall\u00e9e de l&#8217;Avon \u00e0 la vall\u00e9e du Kennet. Sur le c\u00f4t\u00e9 ouest de la colline, la pente est raide, et sur le c\u00f4t\u00e9 est, la descente est tr\u00e8s progressive jusqu&#8217;\u00e0 la Tamise \u00e0 Reading. Ces sites sont des exemples tr\u00e8s impressionnants d&#8217;une excellente ing\u00e9nierie de l&#8217;\u00e9poque de leur construction. Le fait qu&#8217;ils travaillent tous encore aujourd&#8217;hui t\u00e9moigne \u00e0 la fois de la qualit\u00e9 du travail original et de l&#8217;entretien dont ils ont b\u00e9n\u00e9fici\u00e9 pendant plus de 200 ans.<\/p>\n<p>Pendant la Seconde Guerre Mondiale, les forces militaires ont arm\u00e9 le canal comme ligne de d\u00e9fense en cas d&#8217;invasion de l&#8217;Angleterre par le sud. \u00a0De nombreux bunkers en b\u00e9ton contenant des canons de campagne ont \u00e9t\u00e9 construits en 1940 sur la rive nord du canal. \u00a0Heureusement, ils n&#8217;ont pas vu d&#8217;action, mais ils restent comme des rappels silencieux de leur temps. [5].<\/p>\n<p>Marcher le long du canal permet d&#8217;appr\u00e9cier le travail des gens du pass\u00e9, en particulier ceux qui l&#8217;ont construit et ceux qui l&#8217;ont restaur\u00e9. \u00a0En utilisant uniquement des pelles et des brouettes, les navigateurs de 1800 ont creus\u00e9 un canal de 130 kilom\u00e8tres, ainsi que la construction de 105 \u00e9cluses, 300 ponts et d&#8217;autres infrastructures telles que des quais, des cales s\u00e8ches, des ateliers. \u00a0Plus r\u00e9cemment, des b\u00e9n\u00e9voles ont restaur\u00e9 le canal dans son \u00e9tat d&#8217;origine, en utilisant des outils comme ceux de la construction d&#8217;origine.<\/p>\n<p>Aujourd&#8217;hui, le canal Kennet et Avon est un atout important pour le tourisme en Angleterre. C&#8217;est certainement l&#8217;une des attractions touristiques les plus importantes de notre r\u00e9gion et des visiteurs du monde entier.<\/p>\n<style id=\"bwg-style-0\">  #bwg_container1_0 {\t\/*visibility: hidden;*\/  }  #bwg_container1_0 * {\t  -moz-user-select: none;\t  -khtml-user-select: none;\t  -webkit-user-select: none;\t  -ms-user-select: none;\t  user-select: none;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_image_wrap_0 {\t  background-color: #F2F2F2;\t  width: 800px;\t  height: 500px;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_image_0 {\t  max-width: 800px;\t  max-height: 410px;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_embed_0 {\twidth: 800px;\theight: 410px;  }  #bwg_container1_0 #bwg_container2_0 #bwg_slideshow_play_pause_0 {\tbackground: transparent url(\"https:\/\/saint-christophers-hosting.com\/wp-content\/plugins\/photo-gallery\/images\/blank.gif\") repeat scroll 0 0;  }  #bwg_container1_0 #bwg_container2_0 #bwg_slideshow_play_pause-ico_0 {\tcolor: #D6D6D6;\tfont-size: 35px;  }  #bwg_container1_0 #bwg_container2_0 #bwg_slideshow_play_pause-ico_0:hover {\tcolor: #BABABA;  }  #bwg_container1_0 #bwg_container2_0 #spider_slideshow_left_0,  #bwg_container1_0 #bwg_container2_0 #spider_slideshow_right_0 {\tbackground: transparent url(\"https:\/\/saint-christophers-hosting.com\/wp-content\/plugins\/photo-gallery\/images\/blank.gif\") repeat scroll 0 0;  }  #bwg_container1_0 #bwg_container2_0 #spider_slideshow_left-ico_0,  #bwg_container1_0 #bwg_container2_0 #spider_slideshow_right-ico_0 {\t  background-color: #FFFFFF;\t  border-radius: 20px;\t  border: 0px none #FFFFFF;\t  box-shadow: ;\t  color: #D6D6D6;\t  height: 37px;\t  font-size: 12px;\t  width: 37px;\t  opacity: 1.00;  }  #bwg_container1_0 #bwg_container2_0 #spider_slideshow_left-ico_0:hover,  #bwg_container1_0 #bwg_container2_0 #spider_slideshow_right-ico_0:hover {\t  color: #BABABA;  }      #spider_slideshow_left-ico_0{      left: -9999px;    }    #spider_slideshow_right-ico_0{      left: -9999px;    }      #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_image_container_0 {\t  bottom: 90px;\t  width: 800px;\t  height: 500px;\t  }\t  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_filmstrip_container_0 {\t  display: table;\t  height: 90px;\t  width: 800px;\t  bottom: 0;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_filmstrip_0 {\t  left: 20px;\t  width: 760px;\t  \/*z-index: 10106;*\/  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_filmstrip_thumbnails_0 {\t  height: 90px;\t  left: 0px;\t  width: 489px;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_filmstrip_thumbnail_0 {\t  border: 0px none #000000;\t  border-radius: 0;\t  height: 90px;\t  margin: 0px 2px 0 0 ;\t  width: 161px;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_thumb_active_0 {\t  border: 0px solid #FFFFFF;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_thumb_deactive_0 {    opacity: 1.00;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_filmstrip_left_0 {\t  background-color: #F2F2F2;\t  display: table-cell;\t  width: 20px;\t  left: 0;\t  \t    }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_filmstrip_right_0 {\t  background-color: #F2F2F2;\t  right: 0;\t  width: 20px;\t  display: table-cell;\t  \t    }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_filmstrip_left_0 i,  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_filmstrip_right_0 i {\t  color: #BABABA;\t  font-size: 20px;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_watermark_spun_0 {\t  text-align: left;\t  vertical-align: bottom;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_title_spun_0 {\t  text-align: right;\t  vertical-align: top;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_description_spun_0 {\t  text-align: right;\t  vertical-align: bottom;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_watermark_image_0 {\t  max-height: 90px;\t  max-width: 90px;\t  opacity: 0.30;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_watermark_text_0,  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_watermark_text_0:hover {\t  text-decoration: none;\t  margin: 4px;\t  position: relative;\t  z-index: 15;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_title_text_0 {\t  font-size: 16px;\t  font-family: Ubuntu;\t  color: #FFFFFF !important;\t  opacity: 0.70;    border-radius: 5px;\t  background-color: #000000;\t  padding: 0 0 0 0;\t  \t\tmargin: 5px;\t  \t    }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_description_text_0 {\t  font-size: 14px;\t  font-family: Ubuntu;\t  color: #FFFFFF !important;\t  opacity: 0.70;    border-radius: 0;\t  background-color: #000000;\t  padding: 5px 10px 5px 10px;\t    }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_description_text_0 * {\ttext-decoration: none;\tcolor: #FFFFFF !important;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_dots_0 {\t  width: 12px;\t  height: 12px;\t  border-radius: 5px;\t  background: #F2D22E;\t  margin: 3px;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_dots_container_0 {\t  width: 800px;\t  bottom: 0;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_dots_thumbnails_0 {\t  height: 18px;\t  width: 54px;  }  #bwg_container1_0 #bwg_container2_0 .bwg_slideshow_dots_active_0 {\t  background: #FFFFFF;\t  border: 1px solid #000000;  }  <\/style>    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_slideshow\"         data-right-click-protection=\"0\"         data-bwg=\"0\"         data-current-url=\"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/1247\"         data-lightbox-url=\"https:\/\/saint-christophers-hosting.com\/wp-admin\/admin-ajax.php?action=GalleryBox&current_view=0&gallery_id=6&tag=0&theme_id=1&shortcode_id=13&sort_by=order&order_by=asc&current_url=https%3A%2F%2Fsaint-christophers-hosting.com%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F1247\"         data-gallery-id=\"6\"         data-popup-width=\"800\"         data-popup-height=\"500\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"13\"              data-gallery-type=\"slideshow\"              data-gallery-id=\"6\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"https:\/\/saint-christophers-hosting.com\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">              <div class=\"bwg_slideshow_image_wrap_0 bwg-container\"       data-lightbox-url=\"https:\/\/saint-christophers-hosting.com\/wp-admin\/admin-ajax.php?action=GalleryBox&current_view=0&gallery_id=6&tag=0&theme_id=1&shortcode_id=13&sort_by=order&order_by=asc&current_url=https%3A%2F%2Fsaint-christophers-hosting.com%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F1247\">          <div class=\"bwg_slideshow_filmstrip_container_0\">        <div class=\"bwg_slideshow_filmstrip_left_0\">          <i class=\"bwg-icon-angle-left\"><\/i>        <\/div>        <div class=\"bwg_slideshow_filmstrip_0 bwg_slideshow_filmstrip\">          <div class=\"bwg_slideshow_filmstrip_thumbnails_0\">                          <div id=\"bwg_filmstrip_thumbnail_0_0\" class=\"bwg_slideshow_filmstrip_thumbnail_0 bwg_slideshow_thumb_active_0\">                <img decoding=\"async\" style=\"width:161px; height:106.84545454545px; margin-left: 0px; margin-top: -8.4227272727273px;\"                     class=\"skip-lazy bwg_filmstrip_thumbnail_img bwg_slideshow_filmstrip_thumbnail_img_0 \"                     src=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/220px-Dundas_Aqueduct_from_south-east_(1).jpg?bwg=1600885063\"                     data-original=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/220px-Dundas_Aqueduct_from_south-east_(1).jpg?bwg=1600885063\"                     onclick=\"bwg_change_image(parseInt(jQuery('#bwg_current_image_key_0').val()), '0', '', '', '0')\"                     image_id=\"32\"                     image_key=\"0\"                     alt=\"Dundas Aqueduct\" \/>              <\/div>                            <div id=\"bwg_filmstrip_thumbnail_1_0\" class=\"bwg_slideshow_filmstrip_thumbnail_0 bwg_slideshow_thumb_deactive_0\">                <img decoding=\"async\" style=\"width:161px; height:98.795454545455px; margin-left: 0px; margin-top: -4.3977272727273px;\"                     class=\"skip-lazy bwg_filmstrip_thumbnail_img bwg_slideshow_filmstrip_thumbnail_img_0 \"                     src=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/220px-Crofton_Pumping_Station_from_canal_to_east_(1).jpg?bwg=1600885063\"                     data-original=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/220px-Crofton_Pumping_Station_from_canal_to_east_(1).jpg?bwg=1600885063\"                     onclick=\"bwg_change_image(parseInt(jQuery('#bwg_current_image_key_0').val()), '1', '', '', '0')\"                     image_id=\"33\"                     image_key=\"1\"                     alt=\"Crofton Pumping Station\" \/>              <\/div>                            <div id=\"bwg_filmstrip_thumbnail_2_0\" class=\"bwg_slideshow_filmstrip_thumbnail_0 bwg_slideshow_thumb_deactive_0\">                <img decoding=\"async\" style=\"width:161px; height:122.21363636364px; margin-left: 0px; margin-top: -16.106818181818px;\"                     class=\"skip-lazy bwg_filmstrip_thumbnail_img bwg_slideshow_filmstrip_thumbnail_img_0 \"                     src=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/220px-Caen.hill_.locks_.in_.devizes.arp__(1).jpg?bwg=1600885063\"                     data-original=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/220px-Caen.hill_.locks_.in_.devizes.arp__(1).jpg?bwg=1600885063\"                     onclick=\"bwg_change_image(parseInt(jQuery('#bwg_current_image_key_0').val()), '2', '', '', '0')\"                     image_id=\"34\"                     image_key=\"2\"                     alt=\"Caen Hill Locks\" \/>              <\/div>                        <\/div>        <\/div>        <div class=\"bwg_slideshow_filmstrip_right_0\">          <i class=\"bwg-icon-angle-right\"><\/i>        <\/div>      <\/div>          <div id=\"bwg_slideshow_image_container_0\" class=\"bwg_slideshow_image_container_0\" data-params='{\"bwg_source\":\"slider\",\"bwg_current_key\":\"\",\"bwg_transition_duration\":100,\"bwg_trans_in_progress\":false,\"data\":[{\"id\":\"32\",\"alt\":\"Dundas Aqueduct\",\"description\":\"Dundas Aqueduct&amp;lt;br \\\/&amp;gt;\",\"filetype\":\"jpg\",\"filename\":\"220px-Dundas_Aqueduct_from_south-east_(1)\",\"image_url\":\"\\\/imported_from_media_libray\\\/220px-Dundas_Aqueduct_from_south-east_(1).jpg?bwg=1600885063\",\"thumb_url\":\"\\\/imported_from_media_libray\\\/thumb\\\/220px-Dundas_Aqueduct_from_south-east_(1).jpg?bwg=1600885063\",\"redirect_url\":\"\",\"date\":\"2020-09-23 18:15:24\",\"is_embed\":false,\"is_embed_video\":false},{\"id\":\"33\",\"alt\":\"Crofton Pumping Station\",\"description\":\"Crofton Pumping Station&amp;lt;br \\\/&amp;gt;\",\"filetype\":\"jpg\",\"filename\":\"220px-Crofton_Pumping_Station_from_canal_to_east_(1)\",\"image_url\":\"\\\/imported_from_media_libray\\\/220px-Crofton_Pumping_Station_from_canal_to_east_(1).jpg?bwg=1600885063\",\"thumb_url\":\"\\\/imported_from_media_libray\\\/thumb\\\/220px-Crofton_Pumping_Station_from_canal_to_east_(1).jpg?bwg=1600885063\",\"redirect_url\":\"\",\"date\":\"2020-09-23 18:15:46\",\"is_embed\":false,\"is_embed_video\":false},{\"id\":\"34\",\"alt\":\"Caen Hill Locks\",\"description\":\"Caen Hill Locks&amp;lt;br \\\/&amp;gt;\",\"filetype\":\"jpg\",\"filename\":\"220px-Caen.hill_.locks_.in_.devizes.arp__(1)\",\"image_url\":\"\\\/imported_from_media_libray\\\/220px-Caen.hill_.locks_.in_.devizes.arp__(1).jpg?bwg=1600885063\",\"thumb_url\":\"\\\/imported_from_media_libray\\\/thumb\\\/220px-Caen.hill_.locks_.in_.devizes.arp__(1).jpg?bwg=1600885063\",\"redirect_url\":\"\",\"date\":\"2020-09-23 18:16:47\",\"is_embed\":false,\"is_embed_video\":false}],\"width_or_height\":\"width\",\"filmstrip_thumb_margin_hor\":2,\"left_or_top\":\"left\",\"outerWidth_or_outerHeight\":\"outerWidth\",\"enable_slideshow_shuffle\":\"0\",\"lightbox_filmstrip_thumb_border_width\":\"1\",\"thumb_click_action\":\"open_lightbox\",\"thumb_link_target\":\"1\",\"upload_url\":\"https:\\\/\\\/saint-christophers-hosting.com\\\/wp-content\\\/uploads\\\/photo-gallery\",\"preload_images\":\"1\",\"slideshow_effect\":\"fade\",\"enable_slideshow_filmstrip\":\"1\",\"event_stack\":\"\",\"preload_images_count\":0,\"image_width\":\"800\",\"image_height\":\"500\",\"filmstrip_direction\":\"horizontal\",\"slideshow_filmstrip_width\":161,\"slideshow_filmstrip_height\":\"90\",\"slideshow_play_pause_btn_size\":\"35\",\"watermark_type\":\"90\",\"watermark_height\":\"90\",\"watermark_font_size\":\"20\",\"slideshow_title_font_size\":\"16\",\"slideshow_description_font_size\":\"14\",\"bwg_playInterval\":\"\",\"slideshow_interval\":5,\"image_right_click\":\"0\",\"enable_slideshow_autoplay\":\"0\",\"enable_slideshow_music\":\"0\",\"bwg_current_filmstrip_pos\":0}'>      <div class=\"bwg_slide_container_0\">        <div class=\"bwg_slide_bg_0\">          <div class=\"bwg_slider_0\">                            <span class=\"bwg_slideshow_image_spun_0\" id=\"image_id_0_32\">                    <span class=\"bwg_slideshow_image_spun1_0\">                      <span class=\"bwg_slideshow_image_spun2_0\">                                                  <a  class=\"bwg-a bwg_lightbox\" href=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/220px-Dundas_Aqueduct_from_south-east_(1).jpg?bwg=1600885063\" data-image-id=\"32\">                          <img decoding=\"async\" id=\"bwg_slideshow_image_0\"                               class=\"skip-lazy bwg_slide bwg_slideshow_image_0 \"                               src=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/220px-Dundas_Aqueduct_from_south-east_(1).jpg?bwg=1600885063\"                               data-original=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/220px-Dundas_Aqueduct_from_south-east_(1).jpg?bwg=1600885063\"                               image_id=\"32\"                               alt=\"Dundas Aqueduct\" \/>                          <\/a>                                                <\/span>                    <\/span>                  <\/span>                <span class=\"bwg_slideshow_image_second_spun_0\">                  <\/span>                <input type=\"hidden\" id=\"bwg_current_image_key_0\" value=\"0\" \/>                          <\/div>        <\/div>      <\/div>              <a class=\"bwg-a\" id=\"spider_slideshow_left_0\" onclick=\"bwg_change_image(parseInt(jQuery('#bwg_current_image_key_0').val()), (parseInt(jQuery('#bwg_current_image_key_0').val()) + 3 - bwg_iterator(0)) % 3, '', '', 0); return false;\"><span id=\"spider_slideshow_left-ico_0\"><span><i class=\"bwg-icon-angle-left bwg_slideshow_prev_btn_0\"><\/i><\/span><\/span><\/a>        <span id=\"bwg_slideshow_play_pause_0\" class=\"bwg_slideshow_play_pause\" style=\"display: ;\"><span><span id=\"bwg_slideshow_play_pause-ico_0\"><i class=\"bwg-icon-play bwg_ctrl_btn_0 bwg_slideshow_play_pause_0\"><\/i><\/span><\/span><\/span>        <a class=\"bwg-a\" id=\"spider_slideshow_right_0\" onclick=\"bwg_change_image(parseInt(jQuery('#bwg_current_image_key_0').val()), (parseInt(jQuery('#bwg_current_image_key_0').val()) + bwg_iterator(0)) % 3, '', '', 0); return false;\"><span id=\"spider_slideshow_right-ico_0\"><span><i class=\"bwg-icon-angle-right bwg_slideshow_next_btn_0\"><\/i><\/span><\/span><\/a>            <\/div>      <\/div>            <\/div>        <\/form>          <style>          #bwg_container1_0 #bwg_container2_0 #spider_popup_overlay_0 {          background-color: #EEEEEE;          opacity: 0.60;          }          <\/style>        <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"971130463\">                <\/div>    <\/div>    <script>      jQuery(function() {        if( typeof bwg_main_ready == 'function' ) {          bwg_main_ready();        }      });    <\/script>    \n<p>Tableau: La route<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"123\"><strong>De<\/strong><\/td>\n<td width=\"170\"><strong>Longueur (kilom\u00e8tres)<\/strong><\/td>\n<td width=\"198\"><strong>Gare de chemin de fer<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"123\"><strong>Bath \u00e0<\/strong><\/td>\n<td width=\"170\">17<\/td>\n<td width=\"198\">Oui<\/td>\n<\/tr>\n<tr>\n<td width=\"123\"><strong>Bradford \u00e0<\/strong><\/td>\n<td width=\"170\">18<\/td>\n<td width=\"198\">Oui<\/td>\n<\/tr>\n<tr>\n<td width=\"123\"><strong>Devizes \u00e0<\/strong><\/td>\n<td width=\"170\">20<\/td>\n<td width=\"198\"><\/td>\n<\/tr>\n<tr>\n<td width=\"123\"><strong>Pewsey \u00e0<\/strong><\/td>\n<td width=\"170\">20<\/td>\n<td width=\"198\">Oui<\/td>\n<\/tr>\n<tr>\n<td width=\"123\"><strong>Gt Bedwyn \u00e0<\/strong><\/td>\n<td width=\"170\">10<\/td>\n<td width=\"198\">Oui<\/td>\n<\/tr>\n<tr>\n<td width=\"123\"><strong>Hungerford \u00e0<\/strong><\/td>\n<td width=\"170\">15<\/td>\n<td width=\"198\">Oui<\/td>\n<\/tr>\n<tr>\n<td width=\"123\"><strong>Newbury \u00e0<\/strong><\/td>\n<td width=\"170\">20<\/td>\n<td width=\"198\">Oui<\/td>\n<\/tr>\n<tr>\n<td width=\"123\"><strong>Woolhampton \u00e0 <\/strong><\/td>\n<td width=\"170\">10<\/td>\n<td width=\"198\">Oui<\/td>\n<\/tr>\n<tr>\n<td width=\"123\"><strong>Theale \u00e0<\/strong><\/td>\n<td width=\"170\">11<\/td>\n<td width=\"198\">Oui<\/td>\n<\/tr>\n<tr>\n<td width=\"123\"><strong>Reading<\/strong><\/td>\n<td width=\"170\">.<\/td>\n<td width=\"198\">Oui<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[1] <a href=\"https:\/\/en.wikipedia.org\/wiki\/Kennet_and_Avon_Canal\">https:\/\/en.wikipedia.org\/wiki\/Kennet_and_Avon_Canal<\/a><\/p>\n[2] <a href=\"https:\/\/www.croftonbeamengines.org\/\">https:\/\/www.croftonbeamengines.org\/<\/a><\/p>\n[3] <a href=\"https:\/\/en.wikipedia.org\/wiki\/National_Cycle_Route_4\">https:\/\/en.wikipedia.org\/wiki\/National_Cycle_Route_4<\/a><\/p>\n[4] <a href=\"https:\/\/en.wikipedia.org\/wiki\/Great_Canal_Journeys\">https:\/\/en.wikipedia.org\/wiki\/Great_Canal_Journeys<\/a><\/p>\n[5] <a href=\"https:\/\/pennypost.org.uk\/2020\/02\/the-role-of-pillboxes-along-the-kennet-avon-canal-during-ww2\">https:\/\/pennypost.org.uk\/2020\/02\/the-role-of-pillboxes-along-the-kennet-avon-canal-during-ww2<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a un an, je me suis \u200b\u200bpromen\u00e9 le long du canal Kennet et Avon de Hungerford \u00e0 Newbury ; une semaine plus tard, j\u2019ai fait une balade de Hungerford \u00e0 Crofton Beam Engines. \u00a0Les trajets \u00e9taient tr\u00e8s agr\u00e9ables,&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"https:\/\/saint-christophers-hosting.com\/index.php\/2020\/09\/23\/une-balade-le-long-du-canal\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":1249,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-1247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-french"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2020\/09\/220px-Caen.hill_.locks_.in_.devizes.arp_.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8rlea-k7","_links":{"self":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/1247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/comments?post=1247"}],"version-history":[{"count":7,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/1247\/revisions"}],"predecessor-version":[{"id":1271,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/1247\/revisions\/1271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/media\/1249"}],"wp:attachment":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/media?parent=1247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/categories?post=1247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/tags?post=1247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}