{"id":1062,"date":"2020-07-27T19:41:59","date_gmt":"2020-07-27T18:41:59","guid":{"rendered":"https:\/\/saint-christophers-hosting.com\/?p=1062"},"modified":"2022-09-20T19:27:01","modified_gmt":"2022-09-20T18:27:01","slug":"lhistoire-dune-chienne-qui-sappelle-ella","status":"publish","type":"post","link":"https:\/\/saint-christophers-hosting.com\/index.php\/2020\/07\/27\/lhistoire-dune-chienne-qui-sappelle-ella\/","title":{"rendered":"L\u2019histoire d\u2019une chienne qui s\u2019appelle Ella"},"content":{"rendered":"<audio class=\"wp-audio-shortcode\" id=\"audio-1062-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2020\/07\/LaChienneElla-01-Trimmed.mp3?_=1\" \/><a href=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2020\/07\/LaChienneElla-01-Trimmed.mp3\">https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2020\/07\/LaChienneElla-01-Trimmed.mp3<\/a><\/audio>\n<p><a href=\"\/wp-content\/uploads\/2020\/07\/20190714_144931451_iOS-2.jpg\"><img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"1063\" data-permalink=\"https:\/\/saint-christophers-hosting.com\/index.php\/2020\/07\/27\/lhistoire-dune-chienne-qui-sappelle-ella\/20190714_144931451_ios-2\/\" data-orig-file=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2020\/07\/20190714_144931451_iOS-2.jpg\" data-orig-size=\"1363,1435\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"20190714_144931451_iOS (2)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2020\/07\/20190714_144931451_iOS-2-973x1024.jpg\" class=\"alignleft size-medium wp-image-1063\" src=\"\/wp-content\/uploads\/2020\/07\/20190714_144931451_iOS-2-285x300.jpg\" alt=\"\" width=\"285\" height=\"300\" srcset=\"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2020\/07\/20190714_144931451_iOS-2-285x300.jpg 285w, https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2020\/07\/20190714_144931451_iOS-2-973x1024.jpg 973w, https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2020\/07\/20190714_144931451_iOS-2-768x809.jpg 768w, https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2020\/07\/20190714_144931451_iOS-2.jpg 1363w\" sizes=\"(max-width: 285px) 100vw, 285px\" \/><\/a>Il y a deux ans ma femme avait l\u2019id\u00e9e de devenir famille d\u2019accueil d\u2019un chien guide d\u2019aveugles. Mais dans notre coin, l\u2019Association des Chiens Guides d\u2019Aveugles n\u2019a aucun chien. Donc, elle a trouv\u00e9 l\u2019Association des Chiens Guides de Sourdes. Vers la fin de novembre 2018, un chiot arrive chez nous. Elle s\u2019appelle Ella, elle est cocker, elle est n\u00e9e le 30 septembre 2018. Elle est tr\u00e8s mignonne, toute petite au bout d\u2019une laisse longue.<\/p>\n<p>Ella est coquine. Tout-de-suite, on a des trous dans les tapis, les pantoufles sont bien m\u00e2ch\u00e9es. Il est difficile de croire qu&#8217;un petit chiot puisse faire autant de d\u00e9g\u00e2ts si rapidement. Mais \u00e9galement elle a gagn\u00e9 nos c\u0153urs. On lui pardonne et d\u00e9cide qu\u2019apr\u00e8s qu\u2019elle sera partie, on c\u00e9l\u00e9bra en rempla\u00e7ant les tapis et les pantoufles. Au fur et \u00e0 mesure, elle se grandit et son comportement s\u2019am\u00e9liore. Les trous dans les tapis restent, mais ils cessent de grandir.<\/p>\n<p>Le plan est que le chiot reste chez nous quinze mois et par la suite elle ira \u00e0 l\u2019Universit\u00e9 de Chiens, pour apprendre nouvelles comp\u00e9tences comme r\u00e9pondre au t\u00e9l\u00e9phone et r\u00e9pondre \u00e0 la porte. La raison pour laquelle un sourd aurait un t\u00e9l\u00e9phone, je sais pas, mais s\u2019il le faisait, il est utile que la chienne puisse le dire \u00e0 son ma\u00eetre, mais je digresse.<\/p>\n<p>Le Covid arrive et le plan est bien perturb\u00e9. Six mois passent et le responsable de l\u2019Association d\u00e9cide qu\u2019Ella peut rester chez nous et quelqu\u2019un viendra chez nous tous les jours pour l\u2019entrainer. Avant de commencer le stage, la chienne doit \u00eatre st\u00e9rilis\u00e9e mais le v\u00e9t\u00e9rinaire ne travaille pas pendant la p\u00e9riode de confinement. Finalement le 22 juillet Ella est st\u00e9rilis\u00e9e. Quel dommage qu\u2019elle ne puisse jamais \u00eatre chienne m\u00e8re. Donc, dans deux semaines, elle entame sa derni\u00e8re formation. Le t\u00e9l\u00e9phone sonnera et il y aura pas mal de coups de porte.<\/p>\n<p>Donc, Ella restera chez nous jusqu\u2019\u00e0 No\u00ebl 2020. En somme, elle aura pass\u00e9 26 mois chez nous contre les 15 mois pr\u00e9vus. C\u2019\u00e9tait un plaisir d&#8217;avoir Ella chez nous. On lui dira au revoir accompagn\u00e9 d\u2019un soupir de regret, pas un soupir de soulagement. Cependant, on ne lui dira pas au revoir tant qu&#8217;elle ne sera pas partie. On ne va pas installer des nouveaux tapis tout-de-suite ; on \u00e9vite de tenter le sort puisse qu&#8217;elle revienne.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a deux ans ma femme avait l\u2019id\u00e9e de devenir famille d\u2019accueil d\u2019un chien guide d\u2019aveugles. Mais dans notre coin, l\u2019Association des Chiens Guides d\u2019Aveugles n\u2019a aucun chien. Donc, elle a trouv\u00e9 l\u2019Association des Chiens Guides de Sourdes. Vers&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"https:\/\/saint-christophers-hosting.com\/index.php\/2020\/07\/27\/lhistoire-dune-chienne-qui-sappelle-ella\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":1063,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"class_list":["post-1062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-french"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/saint-christophers-hosting.com\/wp-content\/uploads\/2020\/07\/20190714_144931451_iOS-2.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8rlea-h8","_links":{"self":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/1062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/comments?post=1062"}],"version-history":[{"count":14,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/1062\/revisions"}],"predecessor-version":[{"id":2912,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/posts\/1062\/revisions\/2912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/media\/1063"}],"wp:attachment":[{"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/media?parent=1062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/categories?post=1062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/saint-christophers-hosting.com\/index.php\/wp-json\/wp\/v2\/tags?post=1062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}